{"id":2500,"date":"2020-03-16T11:50:28","date_gmt":"2020-03-16T10:50:28","guid":{"rendered":"https:\/\/confecomerc.es\/informacion-coronavirus"},"modified":"2021-10-06T09:42:38","modified_gmt":"2021-10-06T08:42:38","slug":"informacion-coronavirus","status":"publish","type":"page","link":"https:\/\/confecomerc.es\/va\/informacion-coronavirus\/","title":{"rendered":"Informaci\u00f3n Coronavirus"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.4.1&#8243;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.4.1&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.4.1&#8243;][et_pb_image src=&#8221;https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/info-coronavirus.png&#8221; _builder_version=&#8221;4.4.1&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.4.1&#8243;][et_pb_image src=&#8221;https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/banner-infocoronavirus.gva_.es-y-telefono-1.png&#8221; _builder_version=&#8221;4.4.1&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_2,1_4&#8243; _builder_version=&#8221;4.4.1&#8243;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.4.1&#8243;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.4.1&#8243;][et_pb_image src=&#8221;https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/COMERCIOSABIERTOS_bannerWEB3.jpg&#8221; url=&#8221;https:\/\/confecomerc.es\/va\/comerciosabiertoscercadeti\/&#8221; _builder_version=&#8221;4.4.1&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.4.1&#8243;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.4.6&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;]<\/p>\n<p>Con el fin de dar una informaci\u00f3n m\u00e1s \u00e1gil y de inter\u00e9s en apoyo al sector del peque\u00f1o comercio, en este web se actualizar\u00e1 toda la documentaci\u00f3n relativa al COVID-19, oficial, y espec\u00edfica de car\u00e1cter comercial, laboral, econ\u00f3mico y fiscal, as\u00ed como gu\u00edas y manuales sobre recomendaciones y buenas pr\u00e1cticas para el desarrollo de la actividad comercial. Os invitamos a que consult\u00e9is peri\u00f3dicamente este espacio, al tiempo que mantenemos todos nuestros canales habituales, con el fin de prestar la m\u00e1xima atenci\u00f3n, comunicaci\u00f3n y servicio.<\/p>\n<p><strong><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/telfwebCOVID19.pdf\">COVID-19: CONTACTOS Y WEBS DE INFORMACI\u00d3N<\/a><\/strong><\/p>\n<p><a href=\"http:\/\/confecomercnews.es\/images\/files\/epis30042020.pdf\"><strong>PROVEEDORES EPI Y OTROS EQUIPOS DE PROTECCI\u00d3N PARA EL COMERCIO<\/strong><\/a><\/p>\n<p>[\/et_pb_text][et_pb_toggle title=&#8221;INFORMACI\u00d3N DESESCALADA Y NUEVA NORMALIDAD&#8221; _builder_version=&#8221;4.4.6&#8243;]<\/p>\n<ul>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/06\/NuevaNormalidad_GVA.pdf\">\u00bfQu\u00e9 se puede hacer en la nueva normalidad? Indicaciones Generales GVA<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/05\/20\/pdfs\/BOE-A-2020-5142.pdf\">Orden SND\/422\/2020, de 19 de mayo que regula las condiciones para el uso obligatorio de mascarilla mientras dure la situaci\u00f3n de crisis sanitaria ocasionada por el COVID-19<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/05\/16\/pdfs\/BOE-A-2020-5088.pdf\">Orden SND\/414\/2020, de 16 de mayo, para la flexibilizaci\u00f3n de determinadas restricciones de \u00e1mbito nacional establecidas tras la declaraci\u00f3n del estado de alarma en aplicaci\u00f3n de la fase 2 del Plan para la transici\u00f3n hacia una nueva normalidad. <\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/Conse_Municipisfase1_CAS.pdf\">Municipios y Departamentos de Salud que pasan a la Fase 1 desde el 11 de mayo en la Comunidad Valenciana<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/CONSE_fase1_CAS.pdf\">ACTIVIDADES EN LA FASE 1 DE DESESCALADA DESDE EL 11 DE MAYO<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/fase1_comercio_08052020.pdf\">CONFECOMER\u00c7 CV: Comercios y condiciones para la apertura en la fase 1 de desescalada<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/BOE-A-2020-4911.pdf\">Orden SND\/399\/2020, de 9 de mayo, para la flexibilizaci\u00f3n de determinadas restricciones de \u00e1mbito nacional, establecidas tras la declaraci\u00f3n del estado de alarma en aplicaci\u00f3n de la fase 1 del Plan para la transici\u00f3n hacia una nueva normalidad<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/fase0_comercio_03052020.pdf\"><strong>CONFECOMER\u00c7 CV: Comercios y condiciones de la reapertura a partir del lunes 4 de mayo (Fase 0)<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/2020_05_03_Preguntas_y_respuestas_plan_nueva_normalidad.pdf\">PLAN PARA LA TRANSICI\u00d3N HACIA UNA NUEVA NORMALIDAD: RESPUESTAS A PREGUNTAS FRECUENTES<\/a><\/li>\n<li><a href=\"https:\/\/www.mincotur.gob.es\/es-es\/COVID-19\/Documents\/Protocolo_y_Guia_de_buenas_practicas_para_establecimientos_de_comercio.pdf\">PROTOCOLO Y GU\u00cdA DE BUENAS PR\u00c1CTICAS DIRIGIDAS A LA ACTIVIDAD COMERCIAL EN ESTABLECIMIENTO F\u00cdSICO Y NO SEDENTARIO<\/a><\/li>\n<li><a href=\"http:\/\/www.pateco.org\/administracion\/ficheros\/Recomendaciones%20para%20la%20reapertura%20de%20comercios.pdf\">Recomendaciones para la reapertura de comercios &#8211; Oficina PATECO<\/a><\/li>\n<li><a href=\"http:\/\/www.indi.gva.es\/documents\/161328150\/169707556\/PELUQUERIAS+-+GUIA+DE+RECOMENDACIONES+HIGIENICO+SANITARIAS+COVID+19+-+STANPA.pdf\/5e2292cb-a7cd-445d-8cdb-5337e4f3de5e\">Recomendaciones higi\u00e9nico sanitarias para salones de peluquer\u00eda<\/a><\/li>\n<li><a href=\"http:\/\/www.indi.gva.es\/documents\/161328150\/169707556\/GUIA+PRACTICAS+SEGURAS+COMERCIO_ver2.pdf\/7b192ef2-0f3b-4410-ba8c-fceeafe3971c\">GU\u00cdA DE PR\u00c1CTICAS SEGURAS ANTES EL SARS-CoV-2: Abrir un comercio al p\u00fablico en tiempos de coronavirus<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/GUIA-PRACTICAS-SEGURAS-COMERCIO.pdf\">MARCADORES QUE INDICAR\u00c1N CU\u00c1NDO UN TERRITORIO PUEDE AVANZAR DE FASE, DEBE MANTENERSE O RETROCEDER<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/PLAN-TRANSICION.jpeg\">PLAN PARA LA TRANSICI\u00d3N HACIA UNA NUEVA NORMALIDAD (IMAGEN)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/TRANSICION-COMERCIO-MINORISTA.jpeg\">PLAN PARA LA TRANSICI\u00d3N HACIA UNA NUEVA NORMALIDAD: COMERCIO MINORISTA Y PRESTACI\u00d3N DE SERVICIOS<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/DESESCALADA_-ACTIVIDADES-CULTURALES-Y-DE-OCIO.jpeg\">PLAN PARA LA TRANSICI\u00d3N HACIA UNA NUEVA NORMALIDAD: ACTIVIDADES CULTURALES Y DE OCIO<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/PlanTransicionNuevaNormalidad.pdf\">PLAN PARA LA TRANSICI\u00d3N HACIA UNA NUEVA NORMALIDAD (28\/04\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/200428-COMPARECENCIA-PG-CMIN.pdf\">RESUMEN COMPARECENCIA PRESIDENTE DEL GOBIERNO PLAN PARA LA TRANSICI\u00d3N HACIA UNA NUEVA NORMALIDAD (28\/04\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/28042020_Anexo-I-PANEL-DE-INDICADORES.pdf\">ANEXO I.- PANEL DE INDICADORES INTEGRAL<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/28042020_Anexo-III-CRONOGRAMA_plantransicion.pdf\">ANEXO III.- CRONOGRAMA ORIENTATIVO PARA LA TRANSICI\u00d3N HACIA UNA NUEVA NORMALIDADPLAN PARA LA TRANSICI\u00d3N HACIA UNA NUEVA NORMALIDAD: ACTIVIDADES CULTURALES Y DE OCIO<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;DOCUMENTACI\u00d3N OFICIAL&#8221; _builder_version=&#8221;4.4.6&#8243;]<\/p>\n<p><strong><a href=\"https:\/\/boe.es\/biblioteca_juridica\/codigos\/codigo.php?id=355&amp;modo=2&amp;nota=0\">&#8211; Crisis Sanitaria COVID-19 (normativa consolidada)<\/a><\/strong><\/p>\n<p><em>\u2013 DECRETOS<\/em><\/p>\n<ul>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/BOE-A-2020-4208.pdf.pdf\">Real Decreto-ley 11\/2020, de 31 de marzo, por el que se adoptan medidas urgentes complementarias en el \u00e1mbito social y econ\u00f3mico para hacer frente al COVID-19.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/03\/29\/pdfs\/BOE-A-2020-4166.pdf\">Real Decreto-ley 10\/2020, de 29 de marzo, por el que se regula un permiso retribuido recuperable para las personas trabajadoras por cuenta ajena que no presten servicios esenciales, con el fin de reducir la movilidad de la poblaci\u00f3n en el contexto de la lucha contra el COVID-19<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/03\/18\/pdfs\/BOE-A-2020-3828.pdf\">Real Decreto 465\/2020, de 17 de marzo, por el que se modifica el Real Decreto 463\/2020, de 14 de marzo, por el que se declara el estado de alarma para la gesti\u00f3n de la situaci\u00f3n de crisis sanitaria ocasionada por el COVID-19.<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/03\/18\/pdfs\/BOE-A-2020-3824.pdf\">Real Decreto-ley 8\/2020, de 17 de marzo, de medidas urgentes extraordinarias para hacer frente al impacto econ\u00f3mico y social del COVID-19<\/a><\/li>\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/1RCUM4y-_cAgJ0rpgget0LpZD7fcqRBHT\/view\">REAL DECRETO 463\/2020 DE 14 DE MARZO POR ESTADO DE ALARMA (14\/03\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/03\/13\/pdfs\/BOE-A-2020-3580.pdf\">Real Decreto-ley 7\/2020, de 12 de marzo, por el que se adoptan medidas urgentes para responder al impacto econ\u00f3mico del COVID-19<\/a><\/li>\n<\/ul>\n<p>\u2013 ORDENES MINISTERIALES<\/p>\n<ul>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/BOE-A-2020-4911.pdf\">Orden SND\/399\/2020, de 9 de mayo, para la flexibilizaci\u00f3n de determinadas restricciones de \u00e1mbito nacional, establecidas tras la declaraci\u00f3n del estado de alarma en aplicaci\u00f3n de la fase 1 del Plan para la transici\u00f3n hacia una nueva normalidad<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/BOE-A-2020-4690.pdf\">Orden ISM\/371\/2020, de 24 de abril, por la que se desarrolla el art\u00edculo 34 del Real Decreto-ley 11\/2020, de 31 de marzo, por el que se adoptan medidas urgentes complementarias en el \u00e1mbito social y econ\u00f3mico para hacer frente al COVID-19.<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/BOE-A-2020-3948.pdf\">Orden TMA\/264\/2020, de 20 de marzo, por la que se modifica la Orden TMA\/ 259\/2020, de 19 de marzo, por la que se dictan instrucciones sobre transporte por carretera<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/BOE-A-2020-3892.pdf\">Orden SND\/257\/2020, de 19 de marzo, por la que se declara la suspensi\u00f3n de apertura al p\u00fablico de establecimientos de alojamiento tur\u00edstico, de acuerdo con el art\u00edculo 10.6 del Real Decreto 463\/2020, de 14 de marzo, por el que se declara el estado de alarma para la gesti\u00f3n de la situaci\u00f3n de crisis sanitaria ocasionada por el COVID-19<\/a><\/li>\n<\/ul>\n<p>\u2013 CONSEJO DE MINISTROS<\/p>\n<ul>\n<li><a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/03\/26\/pdfs\/BOE-A-2020-4070.pdf\">Resoluci\u00f3n de 25 de marzo de 2020, de la Secretar\u00eda de Estado de Econom\u00eda y Apoyo a la Empresa, por la que se publica el Acuerdo del Consejo de Ministros de 24 de marzo de 2020, por el que se aprueban las caracter\u00edsticas del primer tramo de la l\u00ednea de avales del ICO para empresas y aut\u00f3nomos, para paliar los efectos econ\u00f3micos del COVID-19. <\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/Referencia-Consejo-de-Ministros-24_3_2020.pdf\">Referencia del Consejo de Ministros 24 \/3\/2020: L\u00cdNEA DE AVALES PARA GARANTIZAR LA LIQUIDEZ DE AUT\u00d3NOMOS Y EMPRESAS,<\/a><\/li>\n<\/ul>\n<p><em>\u2013 BOE<\/em><\/p>\n<ul>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/BOE-355_Crisis_Sanitaria_COVID-19-1.pdf\">COMPENDIO DE LEGISLACI\u00d3N SOBRE LA &#8220;CRISIS SANITARIA COVID-19 &#8211; BOE del 22 de marzo 2020<\/a><\/li>\n<li><a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/03\/15\/\">DISPOSICIONES PUBLICADAS EN EL BOE (15\/03\/2020)<\/a><\/li>\n<\/ul>\n<p><em>\u2013 DOCUMENTOS, NOTAS DE PRENSA\u2026<\/em><\/p>\n<ul>\n<li><a href=\"http:\/\/www.congreso.es\/public_oficiales\/L14\/CONG\/BOCG\/A\/BOCG-14-A-10-1.PDF\">Proyecto de Ley de medidas urgentes extraordinarias para hacer frente al impacto econ\u00f3mico y social del COVID-19\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/b6ad3d1f-c186-45e1-9fff-db93baf96b24.pdf\">AYUDAS URGENTES A LOS AUTON\u00d3MOS DE LA COMUNITAT VALENCIANA AFECTADOS POR LA CRISIS SANITARIA OCASIONADA POR LA COVID-19 <\/a><\/li>\n<li><a href=\"http:\/\/confecomercnews.es\/images\/files\/Ampliacio%CC%81n%20Criterio%20Interpretativo%20DG%20de%20Trabajo%20sobre%20ERTE%20de%20fuerza%20mayor.pdf\">OFICIO DGE-SGON-841CRA: NOTA SOBRE EXPEDIENTES SUSPENSIVOS Y DE REDUCCI\u00d3N DE JORNADA POR COVID-19( CONTINUACI\u00d3N): 28\/03\/2020<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/200319-INFORME-CUESTIONES-RELACIONADAS-REAL-DECRETO-463_20_SGM-1.pdf\">INFORME: RESPUESTAS A CUESTIONES PLANTEADAS SOBRE LA INTERPRETACI\u00d3N DEL RD 463\/2020, MODIFICADO POR REAL DECRETO 465\/2020 &#8211; (Ministerio de Justicia, 20\/03\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/20200300-INFORME-CITCO-FAKE-NEWS-CORONAVIRUS-2-231-956-2.pdf.pdf.pdf\">Informe Fake News y desinformaciones sobre el Covid-19 en fuentes abiertas (Ministerio del Interior, 17\/03\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/Alternativas-Escasez-EPI.pdf\">Medidas excepcionales ante la posible escasez de EPI: estrategias alternativas en situaci\u00f3n de crisis<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/Refuerzo-del-Plan-de-Choque-econ%C3%B3mico-por-el-COVID-19.pdf\">Refuerzo del Plan de Choque econ\u00f3mico por el COVID-19: El Gobierno moviliza 200.000 millones de euros para apoyar a trabajadores, familias y empresarios (17\/03\/2020)<\/a><\/li>\n<\/ul>\n<p><em>\u2013 DOGV<\/em><\/p>\n<ul>\n<li><a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/04\/04\/pdf\/2020_2813.pdf\">Decreto 44\/2020, de 3 de abril, del Consell, de aprobaci\u00f3n de las Bases Reguladoras de concesi\u00f3n directa de ayudas urgentes a personas trabajadoras en r\u00e9gimen de aut\u00f3nomo afectadas por la COVID-1.<\/a><\/li>\n<li><a href=\"https:\/\/www.dogv.gva.es\/datos\/2020\/04\/01\/pdf\/2020_2766.pdf\">RESOLUCI\u00d3N de 30 de marzo de 2020, de la Conselleria de Econom\u00eda Sostenible, Sectores Productivos, Comercio y Trabajo, por la que se modifican las habilitaciones para la apertura comercial de domingos y festivos durante el per\u00edodo correspondiente a la Semana Santa y Pascua. <\/a><\/li>\n<li><a href=\"https:\/\/www.dogv.gva.es\/datos\/2020\/04\/01\/pdf\/2020_2767.pdf\">RESOLUCI\u00d3N de 30 de marzo de 2020, de la Direcci\u00f3n General de Comercio, Artesan\u00eda y Consumo, por la que se suspenden temporalmente las declaraciones de zona de gran afluencia tur\u00edstica durante el per\u00edodo correspondiente a la Semana Santa y Pascua<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/200401-Nota-aclaratoria-5.pdf\">NOTA INFORMATIVA DEL D\u00cdA 31 DE MARZO DE 2020 DE LA CONSELLERIA DE JUSTICIA, INTERIOR Y ADMINISTRACI\u00d3N P\u00daBLICA SOBRE LAS MEDIDAS PREVENTIVAS EN MATERIA DE ESPECT\u00c1CULOS P\u00daBLICOS, ACTIVIDADES RECREATIVAS, ACTIVIDADES SOCIOCULTURALES Y ESTABLECIMIENTOS P\u00daBLICOS PARA LIMITAR LA PROPAGACI\u00d3N Y CONTAGIO POR EL COVID-19<\/a><\/li>\n<li><a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/03\/30\/pdf\/2020_2740.pdf\">DECRETO LEY 1\/2020, de 27 de marzo, del Consell, de medidas urgentes de apoyo econ\u00f3mico y financiero a las personas trabajadoras aut\u00f3nomas, de car\u00e1cter tributario y de simplificaci\u00f3n administrativa, para hacer frente al impacto de la Covid-19<\/a><\/li>\n<li><a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/03\/13\/pdf\/2020_2526.pdf\">DOGV- 13\/03\/2020: Suspensi\u00f3n temporal de la actividad educativa y formativa presencial<\/a><\/li>\n<li><a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/03\/13\/pdf\/2020_2560.pdf\">DOGV- 13\/03\/2020: Medidas excepcionales para acontecimientos de car\u00e1cter cultural, recreativo o de ocio cierre de centros culturales<\/a><\/li>\n<li><a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/03\/13\/pdf\/2020_2561.pdf\">DOGV- 13\/03\/2020: Medidas especiales de car\u00e1cter preventivo en materia de espect\u00e1culos p\u00fablicos, actividades recreativas, actividades socioculturales y establecimientos p\u00fablicos<\/a><\/li>\n<li><a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/03\/12\/pdf\/2020_2446.pdf\">DOGV \u2013 12\/03\/2020: Medidas excepcionales para eventos festivos y de concentraci\u00f3n de personas, en la Comunitat Valenciana<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;AYUDAS&#8221; _builder_version=&#8221;4.4.6&#8243;]<\/p>\n<p><strong><a href=\"http:\/\/planhope.gva.es\/\">PLAN HOPE: Buscador y orientador de ayudas para la reactivaci\u00f3n econ\u00f3mica y social de la Comunitat Valenciana<\/a><\/strong><\/p>\n<p><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/CIRCULAR-AYUDAS-CONFECOMERC.pdf\"><strong>Cuadro resumen ayudas nacionales y auton\u00f3micas ante el Covid-19<\/strong><\/a><\/p>\n<p><em>\u2013 AYUDAS DIRECTAS:<\/em><\/p>\n<ul>\n<li><a href=\"https:\/\/divaladl.es\/va\/noticia\/ver\/mesures-socioeconomiques-efectes-covid19\/20422\">Mesures econ\u00f2miques contra els efectes de la #COVID19 (Diputaci\u00f3 de Val\u00e8ncia)<\/a><\/li>\n<li><a href=\"https:\/\/revista.seg-social.es\/2020\/03\/23\/como-solicitar-la-nueva-prestacion-extraordinaria-para-autonomos-afectados-por-el-covid-19\/\">Prestaci\u00f3n extraordinaria por cese de actividad (Nacional)<\/a><\/li>\n<li><a href=\"https:\/\/www.bonosocial.gob.es\/\">Bono Social Aut\u00f3nomos (Nacional) <\/a><\/li>\n<li><a href=\"http:\/\/www.labora.gva.es\/es\/empreses\/busque-ajudes-subvencions\/ajudes-foment-de-l-ocupacio\/-\/asset_publisher\/eLgUuSsd70Zp\/content\/eaucov-2020-ayuda-extraordinaria-a-personas-trabajadoras-autonomas-covid19?redirect=http%3A%2F%2Fwww.labora.gva.es%2Fes%2Fempreses%2Fbusque-ajudes-subvencions%2Fajudes-foment-de-l-ocupacio%3Fp_p_id%3D101_INSTANCE_eLgUuSsd70Zp%26p_p_lifecycle%3D0%26p_p_state%3Dnormal%26p_p_mode%3Dview%26p_p_col_id%3Dcolumn-1%26p_p_col_pos%3D2%26p_p_col_count%3D3\">Ayudas urgentes a aut\u00f3nomos afectados por el Covid-19 (Auton\u00f3mico) <\/a><\/li>\n<li><a href=\"http:\/\/www.turisme.gva.es\/opencms\/opencms\/turisme\/es\/contents\/home\/noticia\/noticia_1587128530000.html\">Ayudas Conselleria de Turismo (Auton\u00f3micas)\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/2020_3138.pdf\">Ayudas urgentes a personas trabajadoras en r\u00e9gimen aut\u00f3nomo, y peque\u00f1as y medianas empresas del sector tur\u00edstico<\/a><\/li>\n<\/ul>\n<p>\u2013 L\u00cdNEA DE CR\u00c9DITO<\/p>\n<ul>\n<li><a href=\"https:\/\/www.ico.es\/web\/ico\/linea-avales\">L\u00ednea de avales ICO (Nacional)<\/a><\/li>\n<\/ul>\n<p>\u2013 L\u00cdNEA DE PR\u00c9STAMO<\/p>\n<ul>\n<li><a href=\"https:\/\/prestamos.ivf.es\/prestamos\/linea-financiacion-bonificada-ivf-autonomos-y-microempresas\/\">L\u00ednea bonificada IVF aut\u00f3nomos y empresas (Auton\u00f3mico) <\/a><\/li>\n<li><a href=\"https:\/\/prestamos.ivf.es\/prestamos\/linea-financiacion-bonificada-ivf-pyme\/\">L\u00ednea bonificada IVF pyme (Auton\u00f3mico)<\/a><\/li>\n<\/ul>\n<p><em>\u2013 MORATORIAS Y APLAZAMIENTOS <\/em><\/p>\n<ul>\n<li><a href=\"http:\/\/www.mineco.gob.es\/portal\/site\/mineco\/menuitem.b6c80362d9873d0a91b0240e026041a0\/?vgnextoid=e4bd69e8c9b11710VgnVCM1000001d04140aRCRD\">Aplazamiento de impuestos para pymes y aut\u00f3nomos (Nacional) <\/a><\/li>\n<li><a href=\"http:\/\/www.seg-social.es\/wps\/portal\/wss\/internet\/FAQ\/897e30db-3172-4528-987f-ab1ffde1b8e7\/ed13c2a7-72fb-4831-83b5-7c597923e568\/5e520087-dc2f-4375-9221-43a9fdb62658\">Moratoria en el pago y aplazamientos con la Seguridad Social (Nacional) <\/a><\/li>\n<\/ul>\n<p><em>\u2013 OTROS\u00a0<\/em><\/p>\n<ul>\n<li><a href=\"http:\/\/www.mitramiss.gob.es\/ficheros\/ministerio\/contacto_ministerio\/FAQ_ERTES_derivados_coronavirus.pdf\">Solicitud de ERTE (Nacional)\u00a0<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;INFORMACI\u00d3N COMERCIAL&#8221; _builder_version=&#8221;4.4.1&#8243;]<\/p>\n<ul>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/FAQ-ESTADO-ALARMA-01-04-2020-12.44.pdf\">FAQ CONFECOMER\u00c7: PREGUNTAS FRECUENTES SOBRE EL ESTADO DE ALARMA \u2013 Actualizado 01\/04\/2020 a las 12:44h<\/a><\/li>\n<li><a href=\"http:\/\/infocoronavirus.gva.es\/p_negocio.aspx\">Si tienes un negocio o comercio abiertos &#8211; preguntas (Conselleria Econom\u00eda)\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/www.youtube.com\/watch?v=wKah3C-l-T4&amp;feature=youtu.be\">V\u00eddeo Respuestas para empresas: ERTES por fuerza mayor, cotizaciones, excepciones, obligaciones (Conselleria Econom\u00eda GVA -24\/03\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/www.mincotur.gob.es\/es-es\/Paginas\/Contacto-Comercio-Covid19.aspx\">Consultas y preguntas frecuentes sobre Comercio &#8211; Ministerio de Industria, Comercio y Turismo<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/INFORMACIO%CC%81N-PARA-LAS-EMPRESAS_22_03-DEF.pdf\">INFORMACI\u00d3N PARA LAS EMPRESAS: HACER FRENTE AL CORONAVIRUS &#8211; Direcci\u00f3 General de Salut P\u00fablica i Addiccions GVA (22\/03\/2020)<\/a><\/li>\n<li><a href=\"http:\/\/confecomercnews.es\/images\/files\/DUDAS%20SUSPENSI%C3%93N%20COMERCIO.pdf\">PREGUNTAS ACERCA DE LA APERTURA COMERCIAL SEG\u00daN REAL DECRETO 463\/2020 DE 14 DE MARZO POR EL QUE SE DECLARA EL ESTADO DE ALARMA PARA LA GESTI\u00d3N DE LA SITUACI\u00d3N DE CRISIS SANITARIA POR EL COVID-19<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/FAQs-EN-RESPUESTA-A-LAS-CONSULTAS-FORMULADAS-A-MINCOTUR-EN-RELACI%C3%93N-CON-EL-ESTADO-DE-ALARMA-.pdf\">FAQs EN RESPUESTA A LAS CONSULTAS FORMULADAS A MINCOTUR EN RELACI\u00d3N CON EL ESTADO DE ALARMA- ACTUALIZACI\u00d3N 19\/03\/2020 A 17:00h<\/a><\/li>\n<li><a href=\"http:\/\/confecomercnews.es\/images\/files\/Nota%20aclaratoria%20Servicio%20Comidas%20para%20llevar%281%29.pdf\">Nota aclaratoria respecto al servicio de comidas para llevar (15\/03\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/117AngC4BPFNr11VbqG16KeDOgovW9zeX\/view\">Certificado de pertenencia del trabajador\/a a la empresa a efectos de desplazamiento al centro de trabajo<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;RECOMENDACIONES-BUENAS PR\u00c1CTICAS&#8221; _builder_version=&#8221;4.4.1&#8243;]<\/p>\n<ul>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/GUIA-PARA-EL-DESARROLLO-DE-LA-ACTIVIDAD-COMERCIAL-A-DISTANCIA-Y-EN-ZONAS-RURALES.pdf.pdf\">GUIA DE RECOMENDACIONES PARA EL DESARROLLO DE LA ACTIVIDAD COMERCIAL A DISTANCIA Y ABASTECIMIENTO DE ZONAS RURALES SIN LOCALES COMERCIALES<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/200324-PrevencionRRLL_COVID-19.pdf\">PROCEDIMIENTO DE ACTUACI\u00d3N PARA LOS SERVICIOS DE PREVENCION DE RIESGOS LABORALES FRENTE A LA EXPOSICI\u00d3N AL CORONAVIRUS (SARS-COV-2) &#8211; Ministerio de Sanidad &#8211; 24\/03\/2020<\/a><\/li>\n<li>V\u00cdDEO DE APOYO AL PEQUE\u00d1O COMERCIO (<a href=\"http:\/\/confecomercnews.es\/images\/files\/apoyo_comercio_castellano.mp4\">Castellano<\/a>) (<a href=\"http:\/\/confecomercnews.es\/images\/files\/apoyo_comercio_valenciano.mp4\">Valenciano<\/a>)<\/li>\n<li><a href=\"http:\/\/confecomercnews.es\/images\/files\/APOYA-AL-PEQUE%C3%91O-COMERCIO-DESDE-CASA%281%29.jpg\">CAMPA\u00d1A DE APOYO AL PEQUE\u00d1O COMERCIO DESDE CASA\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/Alternativas-Escasez-EPI.pdf\">Medidas excepcionales ante la posible escasez de EPI: estrategias alternativas en situaci\u00f3n de crisis<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/FAQ-comercio-17.03.2020.pdf\">CONSELLERIA COMERCIO PREGUNTAS Y RESPUESTAS M\u00c1S FRECUENTES SOBRE COMERCIO (FAQ): DECLARACI\u00d3N DEL ESTADO DE ALARMA POR EL CORONAVIRUS COVID-19\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/PROTOCOLO-DE-ACTUACI%C3%93N-EN-EL-COMERCIO.jpg\">\u00abProtocolo de actuaci\u00f3n en mercados y comercios de alimentaci\u00f3n\u00bb (Infograf\u00eda)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/RECOMENDACIONES-CEC-COVID-19.pdf\">Manual para el sector comercio frente al escenario Covid-19-Recomendaciones y buenas pr\u00e1cticas\u00a0<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;INFORMACI\u00d3N LABORAL-FISCAL &#8221; _builder_version=&#8221;4.4.1&#8243;]<\/p>\n<ul>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/Buenas-pr\u00e1cticas-en-los-Centros-Trabajo.pdf\">Buenas pr\u00e1cticas en los centros de trabajo (actualizado a 11\/04\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/PrevencionRRLL_COVID-19_8_abril_2020.pdf\">PROCEDIMIENTO DE ACTUACI\u00d3N PARA LOS SERVICIOS DE PREVENCION DE RIESGOS LABORALES FRENTE A LA EXPOSICI\u00d3N AL<br \/>SARS-CoV-2 (08\/02\/2020)<\/a><\/li>\n<li><a href=\"http:\/\/confecomercnews.es\/images\/files\/FAQ%20Laboral%2020-03-2020%2014.30.pdf\">CONFECOMER\u00c7 CV: PREGUNTAS Y RESPUESTAS FRECUENTES EN MATERIAL LABORAL COVID-19 (24\/03\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/PrevencionRRLL_COVID-19-Actualizado-26032020.pdf\">PROCEDIMIENTO DE ACTUACI\u00d3N PARA LOS SERVICIOS DE PREVENCION DE RIESGOS LABORALES FRENTE A LA EXPOSICI\u00d3N AL NUEVO CORONAVIRUS (SARS-COV-2)<\/a> &#8211; 26\/03\/2020<\/li>\n<li><a href=\"http:\/\/confecomercnews.es\/images\/files\/FAQ%20Laboral%2020-03-2020%2014.30.pdf\">CONFECOMER\u00c7 CV: PREGUNTAS Y RESPUESTAS FRECUENTES EN MATERIAL LABORAL COVID-19 (24\/03\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/Nota-Agencia-Tributaria-23_03_2020.pdf\">NOTA AGENCIA TRIBUITARIA VALENCIANA\u00a0 (23-03-2019)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/Instrucci%C3%B3n-DT-Trabajo-GVA-250320.pdf\">INSTRUCCI\u00d3N DE LA DIRECCI\u00d3N GENERAL DE TRABAJO, BIENESTAR Y SEGURIDAD LABORAL DE LA GENERALITAT VALENCIANA EN RELACI\u00d3N A LOS PROCEDIMIENTOS DE SUSPENSI\u00d3N DE CONTRATOS Y REDUCCI\u00d3N DE JORNADA POR CAUSA DE FUERZA MAYOR Y DE SUSPENSI\u00d3N Y REDUCCI\u00d3N DE JORNADA POR CAUSA PRODUCTIVA, ORGANIZATIVA Y T\u00c9CNICA COMO CONSECUENCIA DEL COVID-19<\/a> (23-03-2020)<\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/2020-03-24-Modelo-FORMULARIO-SOLICITUD-PRESTACION-EXTRAORDINARIA-CATA-Editable.pdf\">Formulario de solicitud de la prestaci\u00f3n por cese para aut\u00f3nomos, se incluye a los societarios (modelo unificado para todas las Mutuas)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/FAQ-Laboral-24-03-2020-12.36.pdf\">PREGUNTAS Y RESPUESTAS FRECUENTES EN MATERIAL LABORAL COVID 19 &#8211; CONFECOMER\u00c7 (24\/03\/2020 a las 12:36h)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/Criterio-2-2020-VIRUS-SARS-Co-2.pdf\">CRITERIO 3\/2020 SOBRE DETERMINACI\u00d3N DE LA CONTINGENCIA DE LA SITUACI\u00d3N DE INCAPACIDAD TEMPORAL EN LA QUE SE ENCUENTRAN LOS TRABAJADORES QUE HAN SIDO CONFIRMADOS COMO POSITIVOS EN LAS PRUEBAS DE DETECCI\u00d3N DEL SARS-COV-2<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/CRITERIO-3-2020-Contingencia-Virus-SARS-COV-2-Fdo.pdf\">CRITERIO 3\/2020 SOBRE DETERMINACI\u00d3N DE LA CONTINGENCIA DE LA SITUACI\u00d3N DE INCAPACIDAD TEMPORAL EN LA QUE SE ENCUENTRAN LOS TRABAJADORES QUE HAN SIDO CONFIRMADOS COMO POSITIVOS EN LAS PRUEBAS DE DETECCI\u00d3N DEL SARS-COV-2<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/CRITERIO-ITSS-COVID.pdf\">Criterio Operativo n\u00ba 102\/2020\u00a0 Sobre medidas y actuaciones de la Inspecci\u00f3n de Trabajo y Seguridad Social relativas\u00a0 a situaciones derivadas del nuevo Coronavirus (SARS-CoV-2)\u00a0 Direcci\u00f3n del Organismo Estatal Inspecci\u00f3n de Trabajo y Seguridad Social<\/a><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/GU%C3%8DA-MEDIDAS-LABORALES-EXCEPCIONALES-RDLEY-8-2020.pdf\">GU\u00cdA SOBRE MEDIDAS LABORALES EXCEPCIONALES CONTRA EL COVID-19 APROBADAS POR EL REAL DECRETO-LEY 8\/2020<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/Resumen-ejecutivo-criterio-102-2020-ITSS.pdf\">INFORME EJECUTIVO CEOE: CRITERIO OPERATIVO N\u00ba 102\/2020 SOBRE MEDIDAS Y ACTUACIONES DE LA INSPECCI\u00d3N DE TRABAJO Y SEGURIDAD SOCIAL RELATIVAS A SITUACIONES DERIVADAS DEL NUEVO CORONAVIRUS (SARS-COV-2) \u2013 (18\/03\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/revista.seg-social.es\/2020\/03\/18\/once-preguntas-y-respuestas-sobre-la-nueva-prestacion-extraordinaria-para-autonomos\/\">Once preguntas y respuestas sobre la nueva prestaci\u00f3n extraordinaria para auton\u00f3mos<\/a><\/li>\n<li><a href=\"https:\/\/www.visitvalencia.com\/fundacion-turismo-valencia\/ayudas-economicas-coronavirus\">Medidas econ\u00f3micas y laborales frente al coronavirus (a nivel municipal Val\u00e8ncia, auton\u00f3mico y estatal)<\/a><\/li>\n<li><a href=\"http:\/\/confecomercnews.es\/images\/files\/2020-03-18%20-%20Medidas%20laborales%20-COVID19%20-%20BOE.pdf\">Resumen de Confecomer\u00e7 CV de las medidas laborales del REAL DECRETO-LEY 8\/2020, DE 17 DE MARZO<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/Medidas-flexibilizacion-empresas-COVID-19.pdf\">Resumen de Confecomer\u00e7 CV otras medidas de flexibilizaci\u00f3n del REAL DECRETO-LEY 8\/2020, DE 17 DE MARZO<\/a><\/li>\n<li><a href=\"http:\/\/confecomercnews.es\/images\/files\/NOTA_INTERNA_EXPEDIENTES_DE_REGULACIO%CC%81N_DE_EMPLEO_COVID_19_DGT_FINAL.pdf\">MINISTERIO DE TRABAJO Y ECONOM\u00cdA SOCIAL: NOTA INTERNA EXPEDIENTES SUSPENSIVOS Y REDUCCI\u00d3N DE JORNADA (12\/03\/2020)<\/a><\/li>\n<li><a href=\"http:\/\/confecomercnews.es\/images\/files\/Solicitud%20de%20aplazamiento%20COVID19%20-%20Instrucciones%20provisionales%20AEAT.pdf\">AEAT: Instrucciones provisionales para solicitar el aplazamiento previsto en el Real Decreto Ley COVID-19<\/a><\/li>\n<li><a href=\"https:\/\/twitter.com\/ConfecomercCV\/status\/1239886731513561088\">Bater\u00eda de preguntas frecuentes en el \u00e1mbito del #trabajo elaborado (Conselleria de Comercio GVA)<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;COMUNICADOS Y NOTAS DE PRENSA. PROPUESTAS Y MEDIDAS DEL SECTOR&#8221; _builder_version=&#8221;4.4.6&#8243;]<\/p>\n<ul>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/NP-CEC-21052020.pdf\">COMUNICADO DE CEC ANTE EL ACUERDO PARA DEROGAR LA REFORMA LABORAL<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/NP-Prohibici%C3%B3n-rebajas_CEV.pdf\">La CEV se opone a la restricci\u00f3n impuesta a los establecimientos f\u00edsicos para iniciar las rebajas<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/NP-CEC-1405.pdf\">La CEC exige al Gobierno una aclaraci\u00f3n inmediata sobre la prohibici\u00f3n de las rebajas<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/NP-CEC-3004.pdf\">La CEC exige al Ministerio que rectifique la orden ministerial que delimita las empresas y trabajadores que pueden acogerse a la moratoria de las cotizaciones<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/NOTA-CEC-DESESCALADA.pdf\">La Confederaci\u00f3n Espa\u00f1ola de Comercio acoge con moderado optimismo las medidas aprobadas hoy en el Consejo de Ministros<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/confecomerc-cv-disena-un-espacio-web-que-pone-en-el-mapa-a-los-comercios\/\">Confecomer\u00e7 cv dise\u00f1a un espacio web que pone en el mapa a los comercios de la Comunitat que en este estado de alarma atienden a los clientes ofreciendo su servicio de proximidad (23\/04\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/confecomerc-cv-reclama-seguridad-juridica\/\">Confecomer\u00e7 CV reclama seguridad jur\u00eddica y m\u00e1s medidas para inyectar liquidez a pymes, micropymes y aut\u00f3nomos ante una nueva pr\u00f3rroga del estado de alarma (22\/04\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/NP-CEC_-16042020.pdf\">La CEC pide limitar las ventas online a productos de primera necesidad (16\/04\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/confecomerc-cv-impulsa-la-campana-pequenograngesto\/\">Confecomer\u00e7 CV impulsa la campa\u00f1a #peque\u00f1ograngesto que pone en valor el comercio de proximidad (09\/04\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/confecomerc-cv-reclama-la-colaboracion-de-la-fvmp\/\">Confecomer\u00e7 CV reclama la colaboraci\u00f3n de la FVMP para instar a los ayuntamientos a que impulsen ayudas para el peque\u00f1o comercio ante el impacto del Covid-19 (31\/03\/2020)<\/a><\/li>\n<li><a href=\"http:\/\/prensa.mitramiss.gob.es\/WebPrensa\/noticias\/ministro\/detalle\/3750\">COMUNICADO DEL MINISTERIO DE INCLUSI\u00d3N, SEGURIDAD SOCIAL Y MIGRACIONES (19\/03\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/Comunicado-CEV-reunio%CC%81n-Palau.pdf\">Comunicado CEV: La CEV solicita rapidez y agilidad en la implementaci\u00f3n de lasmedidas incluidas en el Real Decreto Ley para que resulten eficaces (18\/03\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/200317-CEOE-CEPYME-ValoracionMedidasEconomicas.pdf\">CEO-CEPYME: Valoraci\u00f3n del paquete de medidas econ\u00f3micas (17\/03\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/\">CONFECOMER\u00c7 CV DESTACA EL ESFUERZO QUE EST\u00c1 REALIZANDO EL PEQUE\u00d1O COMERCIO Y LOS MERCADOS MUNICIPALES Y LA RESPONSABILIDAD Y ACTITUD DEL SECTOR ANTE LA GRAVE CRISIS<\/a><\/li>\n<li><a href=\"https:\/\/drive.google.com\/file\/d\/1WMXMA5CNda3_lbB3Yoc4RORSGGrrxoxX\/view\">COMUNICADO OFICIAL DE LA CEOE Y CEPYME (15\/03\/2020)<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/nota-informativa-confecomerc-cv-en-relacion-con-covid-19\/\">Nota informativa Confecomer\u00e7 CV en relaci\u00f3n con COVID-19<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/COMUNICADO-DE-LA-CONFEDERACIO%CC%81N-ESPAN%CC%83OLA-DE-COMERCIO-y-recomendaciones-coronavirus.pdf\">COMUNICADO DE LA CONFEDERACI\u00d3N ESPA\u00d1OLA DE COMERCIO (CEC) SOBRE EL CORONAVIRUS Y RECOMENDACIONES<\/a><\/li>\n<li><a href=\"https:\/\/confecomerc.es\/confecomerc-cv-lamenta-el-impacto-que-supone-el-aplazamiento-de-las-fallas\/\">Confecomer\u00e7 CV lamenta el impacto que supone el aplazamiento de las Fallas y la Magdalena<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;CIRCULARES INFORMATIVAS CONFECOMER\u00c7 CV&#8221; _builder_version=&#8221;4.4.6&#8243;]<\/p>\n<p><strong>20\/07\/2020: El uso de la mascarilla pasa a ser obligatorio en el comercio<\/strong><br \/>&#8211; <a href=\"https:\/\/www.dogv.gva.es\/datos\/2020\/07\/18\/pdf\/2020_5852.pdf\">La Conselleria de Sanidad ha aprobado este s\u00e1bado nuevas medidas de seguridad e higiene<\/a><br \/>&#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/Nuevas_medidas_covid_julio_rebrotes.pdf\">Resumen<\/a><\/p>\n<p><strong>10\/07\/2020: La Inspecci\u00f3n de trabajo controlar\u00e1 el cumplimiento de las medidas sanitarias e informe de Sanidad sobre el uso de guantes en alimentaci\u00f3n<\/strong><br \/>&#8211; <a href=\"https:\/\/www.boe.es\/eli\/es\/rdl\/2020\/07\/07\/26\/dof\/spa\/pdf\">Real Decreto Ley 26\/2020, de 7 de julio<\/a> &#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/INSPECCIONTRABAJOSANCIONES.pdf\">M\u00e1s informaci\u00f3n<\/a><br \/>&#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/2.-%20Informe%20utilizaci%C3%B3n%20guantes%20pl%C3%A1stico%20en%20supermercados.pdf\">Sanidad emite un informe sobre el uso de guantes en tiendas de alimentaci\u00f3n<\/a><\/p>\n<p><strong>29\/06\/2020: Pr\u00f3rroga ERTE y regulaci\u00f3n prestaciones y exenciones aut\u00f3nomos<\/strong><br \/>&#8211; <a href=\"https:\/\/boe.es\/boe\/dias\/2020\/06\/27\/pdfs\/BOE-A-2020-6838.pdf\">Real Decreto-ley 24\/2020, de 26 de junio<\/a> &#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/2020-06-27%20-%20Informe%20RD-L%2024-2020.pdf\">M\u00e1s informaci\u00f3n<\/a><\/p>\n<p><strong>26\/06\/2020: Pautas y recomendaciones sanitarias para ejercer la actividad comercial y procedimiento prevenci\u00f3n riesgos<\/strong><br \/>&#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/MedidasComercio_26062020.pdf\">Pautas y recomendaciones sanitarias para ejercer la actividad comercial<\/a><br \/>&#8211; <a href=\"https:\/\/www.mscbs.gob.es\/profesionales\/saludPublica\/ccayes\/alertasActual\/nCov-China\/documentos\/20200619Proteccion_Trabajadores_SARS-CoV-2.pdf\">Actualizaci\u00f3n del Procedimiento de Actuaci\u00f3n de las empresas frente al COVID-19<\/a><\/p>\n<p><strong>22\/06\/2020: La Nueva Normalidad arranca en C. Valenciana sin grandes novedades para el comercio<\/strong><br \/>&#8211; La Nueva Normalidad arranca en la C.Valenciana sin grandes novedades para el comercio <a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/06\/20\/pdf\/2020_4770.pdf\">Acuerdo de 19 de junio, del Consell, sobre medidas de prevenci\u00f3n frente a la Covid-19<\/a><br \/>&#8211; Activado el quinto tramo de la l\u00ednea de avales ICO <a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/06\/17\/pdfs\/BOE-A-2020-6236.pdf\">Resoluci\u00f3n de 16 de junio de 2020, de la Secretar\u00eda de Estado de Econom\u00eda y Apoyo a la Empresa.<\/a><\/p>\n<p><strong>14\/06\/2020: Novedades fase 3 C.Valenciana | Aforo 75% y distancia m\u00ednima de 1,5 m.<\/strong><br \/>&#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/fase3_comercio_13062020.pdf\">Resumen<\/a><br \/>&#8211; <a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/06\/13\/pdf\/2020_4499.pdf\">Decreto<\/a><\/p>\n<p><strong>11\/06\/2020: Novedades fase 3 y nueva normalidad, ayudas, cat\u00e1logo EPI actualizado, y m\u00e1s<\/strong><br \/>&#8211; <a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/06\/10\/pdfs\/BOE-A-2020-5895.pdf\">C\u00f3mo ser\u00e1 la nueva normalidad en el comercio<\/a><br \/>&#8211; Ayudas GVA para que los comercios se adapten a la nueva normalidad (<a href=\"http:\/\/confecomercnews.es\/images\/files\/ayudas_comercio_covid_08062020%281%29.pdf\">Resumen Confecomer\u00e7 CV)<\/a><\/p>\n<p><strong>09\/06\/2020: Nuevas ayudas para comercio, TGSS, webinar medios pago, bater\u00edas de propuestas CEC y m\u00e1s<\/strong><br \/>&#8211; Nuevas ayudas para hacer frente a los gastos ocasionados por COVID-19 &#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/ayudas_comercio_covid_08062020%281%29.pdf\">RESUMEN CONFECOMER\u00c7 CV<\/a><br \/>&#8211; Webinar &#8220;Prepara tu comercio. Conoce las nuevas formas de pago para facilitar que te compren a ti&#8221; <a href=\"https:\/\/docs.google.com\/forms\/d\/1DXNCBrctW-VlXqhsZDvvzUyUm9JGZraoTq3Hnf5-fxg\/viewform?edit_requested=true\">INSCRIPCI\u00d3N SOCIOS<\/a><br \/>&#8211;<a href=\"http:\/\/confecomercnews.es\/images\/files\/Bolet%C3%ADn%2014-2020%20RDL18-2020.pdf\"> Interpretaci\u00f3n TGSS sobre el Real Decreto-ley 18\/2020, de 12 de mayo, de medidas sociales en defensa del empleo<\/a><br \/>&#8211; <a href=\"https:\/\/confecomerc.es\/la-cec-lleva-al-congreso-una-bateria-de-propuestas-para-la-reactivacion-del-pequeno-comercio\/\">La CEC lleva al Congreso una bater\u00eda de propuestas para la reactivaci\u00f3n del peque\u00f1o comercio<\/a><br \/>&#8211; <a href=\"http:\/\/www.valencia.es\/ayuntamiento\/tablon_anuncios.nsf\/vDocumentosWebTablon\/14F94A83E70272B2C125855E002507E0?OpenDocument&amp;lang=1&amp;nivel=5_2\">Ayudas Ayuntamiento Valencia:<\/a> subvenciones en materia de innovaci\u00f3n social y urbana con una orientaci\u00f3n a las MissionsVLC2030, para el ejercicio 2020<\/p>\n<p><strong>08\/06\/2020: Publicadas las bases reguladoras de las ayudas directas a comercio y artesan\u00eda para gastos ocasionados por la crisis del coronavirus<\/strong><br \/>&#8211; Publicadas las bases reguladoras de las ayudas directas a comercio y artesan\u00eda para gastos ocasionados por la crisis del coronavirus <a href=\"http:\/\/confecomercnews.es\/images\/files\/ayudas_comercio_covid_08062020.pdf\">(resumen)<\/a><\/p>\n<p><strong>05\/06\/2020: El Consell aprueba ayudas urgentes de entre 500 y 2.000 euros para hacer frente a los gastos del COVID<\/strong><\/p>\n<p><strong>04\/06\/2020: Advertencia de Sanidad sobre sello COVID FREE, cat\u00e1logo EPI actualizado, NP Confecomer\u00e7 CV y campa\u00f1a Invierte en tu calle<\/strong><br \/>&#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/InfSelloCOVIDFree01062020_firmado.pdf\">Advertencia de Sanidad sobre el sello COVID Free o similar<\/a><br \/>&#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/CUADRO%20EPIS%20PROVEEDORES%2004062020.pdf\">Cat\u00e1logo proveedores EPI Confecomer\u00e7 CV actualizado<\/a><br \/>&#8211; <a href=\"https:\/\/confecomerc.es\/confecomerc-cv-considera-incomprensible-que-no-se-cuente-con-el-comercio-en-la-comision-especial-para-la-reconstruccion-social-economica-y-sanitaria-de-les-corts\/?fbclid=IwAR2TJoNdzVnk6HAVShdBDis7jPoM73sV0PbVt8U6DD6Y-iaGBTB4H5yKe_Q\">CONFECOMER\u00c7 CV: Es incomprensible que el comercio no est\u00e9 en la comisi\u00f3n especial para la Reconstrucci\u00f3n Social, Econ\u00f3mica y Sanitaria de Les Corts<\/a><br \/>&#8211; <a href=\"https:\/\/www.facebook.com\/watch\/?v=2558708421010607\">Campa\u00f1a de apoyo al comercio de proximidad #Invierteentucalle<\/a><\/p>\n<p><strong>03\/06\/2020: Nueva convocatoria de ayudas urgentes en materia de Comercio para hacer frente a las consecuencias del COVID-19<\/strong><\/p>\n<p><strong>02\/06\/2020: Actualizaci\u00f3n medidas fase 2, sello covid free, festivos C.Valenciana y m\u00e1s<\/strong><br \/>&#8211; <a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/05\/30\/pdfs\/BOE-A-2020-5469.pdf\">NOVEDADES Y CONDICIONES EN LA FASE 2 DEL PLAN DE DESESCALADA<\/a><br \/>&#8211; <a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/05\/29\/pdf\/2020_3797.pdf\">Medio centenar de municipios anula o modifica sus festivos locales por coincidir con el estado de alarma<\/a><br \/>&#8211; <a href=\"https:\/\/confecomerc.es\/la-cec-alerta-de-que-los-sellos-covid-free-de-los-comercios\/\">La CEC alerta sobre los sellos &#8220;covid free&#8221; de los comercios<\/a><br \/>&#8211; <a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/06\/02\/pdf\/2020_3943.pdf\">LABORA reactiva la formaci\u00f3n profesional para el empleo en el \u00e1mbito laboral<\/a><br \/>&#8211; <a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/06\/01\/pdfs\/BOE-A-2020-5493.pdf\">Quienes den empleo a beneficiarios del ingreso m\u00ednimo vital tendr\u00e1 el Sello de Inclusi\u00f3n Social<\/a><br \/>&#8211;<a href=\"http:\/\/confecomercnews.es\/images\/files\/Informe%20EREs%20CEV%2027-05-2020.pdf\">Informe sobre los Expedientes de Regulaci\u00f3n de Empleo en la Comunitat Valenciana<\/a><\/p>\n<p><strong>01\/06\/2020: <a href=\"http:\/\/confecomercnews.es\/images\/files\/ayudas_comercio-covid.pdf\">La Direcci\u00f3n General de Comercio deja sin efecto algunas ayudas y permite la modificaci\u00f3n de los proyectos de otras<\/a><\/strong><\/p>\n<p><strong>28\/05\/2020: Novedades fase 2, actualizaci\u00f3n protocolo actuaci\u00f3n comercio y vacaciones para trabajadores en ERTE<\/strong><br \/>&#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/Circular%20resumen%20fase%202.pdf\">Resumen novedades fase 2<\/a><br \/>&#8211; <a href=\"https:\/\/www.mscbs.gob.es\/profesionales\/saludPublica\/ccayes\/alertasActual\/nCov-China\/documentos\/COVID19_Preguntas_y_respuestas_plan_nueva_normalidad.pdf\">Respuesta a preguntas frecuentes<\/a><br \/>&#8211; <a href=\"http:\/\/www.comercio.gob.es\/es-ES\/noticias\/Paginas\/Nuevo-Protocolo-y-Gu%C3%ADa-de-Buenas-pr%C3%A1cticas-dirigida-a-la-actividad-comercial.aspx\">Actualizado el Protocolo y Gu\u00eda de Buenas Pr\u00e1cticas para el comercio<\/a><br \/>&#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/RESUMEN%20DE%20LAS%20VACACIONES%20DE%20LOS%20TRABAJADORES%20EN%20ERTE.pdf\">Vacaciones para los trabajadores en ERTE<\/a><\/p>\n<p><strong>25\/05\/2020: Reanudaci\u00f3n plazos administrativos, modificaci\u00f3n l\u00edneas financiaci\u00f3n bonificada del IVF y actualizaci\u00f3n procedimiento servicio prevenci\u00f3n de riesgos laborales<\/strong><br \/>\u2022 <a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/05\/23\/pdfs\/BOE-A-2020-5240.pdf\">Los plazos administrativos se reanudan a partir del 1 de junio<\/a><br \/>\u2022 <a href=\"https:\/\/www.mscbs.gob.es\/profesionales\/saludPublica\/ccayes\/alertasActual\/nCov-China\/documentos\/PrevencionRRLL_COVID-19.pdf\">Actualizado el procedimiento de actuaci\u00f3n para los servicios de prevenci\u00f3n de riesgos laborales<\/a><br \/>\u2022 Modificaci\u00f3n l\u00edneas financiaci\u00f3n bonificada del IVF: <a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/05\/25\/pdf\/2020_3593.pdf\">Aut\u00f3nomos y microempresas<\/a>, <a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/05\/25\/pdf\/2020_3601.pdf\">PYME<\/a>, <a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/05\/25\/pdf\/2020_3599.pdf\">Gran Empresa<\/a> y <a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/05\/25\/pdf\/2020_3597.pdf\">Liquidez Covid-19<\/a><\/p>\n<p><strong>20\/05\/2020: Obligatoriedad uso mascarilla, cuatro tramo ICO, exenciones en ERTE<\/strong><br \/>\u2022 <a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/05\/20\/pdfs\/BOE-A-2020-5142.pdf\">La mascarilla ser\u00e1 obligatoria en el comercio a partir de ma\u00f1ana: Orden SND\/422\/2020, de 19 de mayo<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/tramo_cuatro_ico_20052020.pdf\">Activado el cuarto tramo de avales a aut\u00f3nomos y pymes<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/ACLARACI%C3%93N%20TGSS.pdf\">Aplicaci\u00f3n exenciones cuotas Segurida Social en ERTE<\/a><\/p>\n<p><strong>19\/05\/2020: Campa\u00f1a #ElFuturoQueCompras, EPIs actualizadas, webinars digitalizaci\u00f3n, novedades fase 1 y m\u00e1s<\/strong><br \/>\u2022 Confecomer\u00e7 CV lanza su campa\u00f1a post-confinamiento para apoyar al peque\u00f1o comercio (<a href=\"https:\/\/www.youtube.com\/watch?v=agcKMpMms1c\">v\u00eddeo pre-lanzamiento<\/a>)<br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/CUADRO%20EPIS%20PROVEEDORES%20190520.pdf\">Actualizamos nuestro cuadro de proveedores de EPI<\/a><br \/>\u2022 <a href=\"https:\/\/docs.google.com\/forms\/u\/2\/d\/1OI5sLpQmfHlTwG_8AN6bWQpnIrHpIPVztmcV2WLW5yo\/edit?usp=drive_open\">Ciclo de webinars &#8220;Digitaliza tu comercio&#8221;<\/a><br \/>\u2022 <a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/05\/16\/pdfs\/BOE-A-2020-5088.pdf\">Tercera actualizaci\u00f3n de la regulaci\u00f3n jur\u00eddica de la desescalada<\/a><br \/>\u2022 <a href=\"http:\/\/confecomerc.es\/primera-fase-del-plan-de-desescalada-en-toda-la-comunitat-valenciana\">Apertura de una gran mayor\u00eda del comercio de la Comunitat en la fase 1<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/Programa%20webinar.pdf\">Webinar &#8220;Mejore sus opciones de liquidaci\u00f3n del Impuesto sobre Sociedades 2019&#8221;. 26 de mayo, 9:00 a 11:30 horas<\/a><\/p>\n<p><strong>17\/05\/2020: Novedades fase 1 | Apertura comercio m\u00e1s 400 m2 y posibilidad rebajas<\/strong><br \/>\u2022 <a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/05\/16\/pdfs\/BOE-A-2020-5088.pdf\">Orden SND\/414\/2020, de 16 de mayo, para la flexibilizaci\u00f3n de determinadas restricciones de \u00e1mbito nacional establecidas tras la declaraci\u00f3n del estado de alarma en aplicaci\u00f3n de la fase 2 del Plan para la transici\u00f3n hacia una nueva normalidad.<\/a><\/p>\n<p><strong>15\/05\/2020: Cat\u00e1logo EPI, pr\u00e9stamos y p\u00f3lizas Sabadell, posici\u00f3n Confecomer\u00e7 CV ante prohibici\u00f3n rebajas y plan Hope<\/strong><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/CUADRO%20EPIS%20PROVEEDORES%20150520.pdf\">Cat\u00e1logo actualizado\u00a0EPI y otros elementos de protecci\u00f3n (15\/05\/2020)<\/a><br \/>\u2022 Sabadell mejora las condiciones de sus pr\u00e9stamos y p\u00f3lizas de cr\u00e9dito por COVID-19: <a href=\"http:\/\/confecomercnews.es\/images\/files\/811%20prestamo%20COVID-19_08casV2.pdf\">Pr\u00e9stamos Sabadell COVID-19<\/a> &#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/811%20poliza%20credito%20COVID-19_08cas%20V2.pdf\">Polizas cr\u00e9dito Sabadell COVID-19<\/a><br \/>\u2022 <a href=\"https:\/\/confecomerc.es\/confecomerc-cv-muestra-su-indignacion-ante-la-prohibicion-de-las-rebajas-en-tienda-fisica\/\">Confecomer\u00e7 CV muestra su indignaci\u00f3n ante la prohibici\u00f3n de las rebajas en tienda f\u00edsica<\/a><br \/>\u2022 <a href=\"http:\/\/planhope.gva.es\/\">La Generalitat crea una plataforma para localizar ayudas para la ciudadan\u00eda y empresas afectadas por COVID-19<\/a><\/p>\n<p><strong>13\/05\/2020: Aclaraci\u00f3n rebajas fase 1, tertulia desescalada, Acuerdo Social y rescates ERTE, IVF y gu\u00eda seguridad comercio<\/strong><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/aclaracion_rebajas_13052020.pdf\">Aclaraci\u00f3n sobre la realizaci\u00f3n de rebajas y promociones en el comercio f\u00edsico<\/a><br \/>\u2022 <a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/12.05.2020-_-Les-not%C3%ADcies-de-la-nit-_-Tert%C3%BAlia.m4a\">Participaci\u00f3n de Confecomer\u00e7 CV en A Punt Radio<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/Comunicacio%CC%81n%20rescates.pdf\">Aprobado el Acuerdo Social para la Defensa del Empleo<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/ivf_prestamo_subordinado_13052020.pdf\">Convocados los pr\u00e9stamos subordinados de IVF<\/a><br \/>\u2022 <a href=\"https:\/\/www.mincotur.gob.es\/es-es\/COVID-19\/Documents\/Protocolo_y_Guia_de_buenas_practicas_para_establecimientos_de_comercio.pdf\">Enlace a la gu\u00eda de seguridad en el comercio y presentaci\u00f3n<\/a><\/p>\n<p><strong>11\/05\/2020: Comercio, hosteler\u00eda y movilidad en fase 1, valoraci\u00f3n Confecomer\u00e7 CV, Acuerdo Social y l\u00ednea ICO<\/strong><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/fase1_comercio_08052020.pdf\">Resumen condiciones reapertura fase 1<\/a><br \/>\u2022 <a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/05\/09\/pdfs\/BOE-A-2020-4911.pdf\">Orden SND\/399\/2020, de 9 de mayo<\/a><br \/>\u2022 <a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/05\/10\/pdfs\/BOE-A-2020-4912.pdf\">Orden TMA\/400\/2020, de 9 de mayo<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/poblaciones_fase1_09052020.pdf\">Areas y poblaciones C. VAlenciana en fase 1<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/carteleria_desescalada_09052020%281%29.pdf\">Carteler\u00eda informativa de Confecomer\u00e7 CV<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/calculo_aforo.jpeg\">C\u00f3mo calcular aforo<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/epis08052020.pdf\">Cuadro proveedores EPI de Confecomer\u00e7 CV<\/a><br \/>\u2022 <a href=\"https:\/\/confecomerc.es\/confecomerc-cv-considera-inadmisible-las-explicaciones-del-gobierno\/\">Valoraci\u00f3n de Confecomer\u00e7 CV de la decisi\u00f3n adoptada por el Gobierno central en relaci\u00f3n a la desescalada de la Comunitat Valenciana<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/acuerdo_social_empleo_11052020.pdf\">Gobierno, patronal y sindicatos firman el Acuerdo Social en Defensa del Empleo<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/tercer_tramo_ico_11052020.pdf\">Tercer tramo l\u00edneas ICO<\/a><\/p>\n<p><strong>10\/05\/2020: Anulaci\u00f3n reincorporacion trabajadores en ERTE en localidades que siguen en Fase 0<\/strong><\/p>\n<p><strong>09\/05\/2020: CONFECOMER\u00c7 CV: Comercios y condiciones para la apertura en la fase 1 de desescalada<\/strong><\/p>\n<p><strong>07\/05\/2009: Piezas carteler\u00eda reapertura comercios y gu\u00edas de recomendaciones actualizadas<\/strong><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/prestamo_ivf_coronavirus_06052020.pdf\">El IVF a\u00f1ade la modalidad CORONAVIRUS al pr\u00e9stamo subordinado a tipo de inter\u00e9s fijo<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/tercer_tramo_avales_06052020.pdf\">Tercer tramo de la l\u00ednea de avales para garantizar la liquidez y reforzar la financiaci\u00f3n empresarial<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/ayudas_libro_arte_06052020.pdf\">Paquete de medidas para el sector cultural afectado por COVID-19<\/a><br \/>\u2022 <a href=\"https:\/\/confecomerc.es\/confecomerc-cv-afronta-el-plan-de-desescalada\/\">Confecomer\u00e7 CV afronta el Plan de Desescalada como el inicio de reactivaci\u00f3n del sector y pide que se ampl\u00ede el l\u00edmite de 400 m2 para determinadadas actividades del peque\u00f1o comercio<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/Recomendaciones%20para%20la%20reapertura%20de%20comercios.pdf\">Gu\u00eda visual de Recomendaciones para la reapertura de los comercios<\/a><\/p>\n<p><strong>06\/05\/2009: Nuevo pr\u00e9stamo IVF, tercer tramo avales ICO, ayudas para librer\u00edas y galer\u00edas de arte y m\u00e1s<\/strong><br \/>\u2022 PIEZAS CARTELER\u00cdA PARA LA REAPERTURA DE LOS COMERCIOS (<a href=\"http:\/\/confecomercnews.es\/news\/lists\/lt.php?tid=fk5WUgNRUA5UAktTX1cFH1EAUldJW1JaUh0EUAECDwIHU1BbCVYYXgBSAwAIB10fA1MFU0lWUwdVHVlbAFMbUQ4HC1QJV1YBVlNTSw0EBwZSUVAFSVEOV1YdVVcDABsBAVQBT1UFBg1SUAIDCwJTBQ\">descargar artes finales<\/a>)<br \/>\u2022 <a href=\"https:\/\/www.mincotur.gob.es\/es-es\/COVID-19\/Documents\/Protocolo_y_Guia_de_buenas_practicas_para_establecimientos_de_comercio.pdf\">Protocolo y gu\u00eda de buenas pr\u00e1cticas para establecimientos de comercio<\/a><br \/>\u2022 <a href=\"http:\/\/www.indi.gva.es\/documents\/161328150\/169707556\/GUIA+PRACTICAS+SEGURAS+COMERCIO_ver2.pdf\/7b192ef2-0f3b-4410-ba8c-fceeafe3971c\">Gu\u00eda de pr\u00e1cticas seguras ante el SARS-Cov-2<\/a><\/p>\n<p><strong>04\/05\/2020:<\/strong> <a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/Protocolo-y-Guia-de-buenas-prA%CC%83%C2%A1cticas-para-establecimientos-de-comercio.pdf\"><strong>Protocolo y gu\u00eda de buenas pr\u00e1cticas en el comercio<\/strong><\/a><br \/><a href=\"https:\/\/www.lamoncloa.gob.es\/serviciosdeprensa\/notasprensa\/sanidad14\/Documents\/2020\/03052020_Desescalada.pdf\">Respuestas a preguntas frecuentes sobre el plan de desescalada del Gobierno<\/a><\/p>\n<p><strong>03\/05\/2020: <a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/fase0_comercio_03052020.pdf\">Comercios y condiciones de la reapertura a partir del lunes 4 de mayo (Fase 0)<\/a><\/strong><\/p>\n<p><strong>02\/05\/2020:<a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/05\/GUIA-PRACTICAS-SEGURAS-COMERCIO.pdf\">GU\u00cdA DE PR\u00c1CTICAS SEGURAS ANTES EL SARS-CoV-2: Abrir un comercio al p\u00fablico en tiempos de coronavirus<\/a><\/strong><\/p>\n<p><strong>30\/04\/2020:<a href=\"http:\/\/confecomercnews.es\/images\/files\/epis30042020.pdf\"> ACTUALIZADO CAT\u00c1LOGO PROVEEDORES EPI Y OTROS EQUIPOS DE PROTECCI\u00d3N PARA EL COMERCIO<\/a><\/strong><\/p>\n<p><strong>29\/04\/2020: Plan del desescalada del Gobierno y moratoria cotizaciones Seguridad Social<\/strong><br \/>\u2022 <a href=\"https:\/\/www.lamoncloa.gob.es\/consejodeministros\/resumenes\/Documents\/2020\/PlanTransicionNuevaNormalidad.pdf\">El Gobierno publica un Plan de Desescalada en 4 fases<\/a><br \/>\u2022 <a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/04\/28\/pdfs\/BOE-A-2020-4690.pdf\">La Seguridad Social aprueba una moratoria de cotizaciones sociales para 12 sectores econ\u00f3micos<\/a><\/p>\n<p><strong>24\/04\/2020: Campa\u00f1a comercios cerca de ti, nuevas l\u00edneas ICO y gu\u00eda ERTE<br \/><\/strong>\u2022 CAMPA\u00d1A COMERCIOS CERCA DE TI (<a href=\"https:\/\/confecomerc.es\/comerciosabiertoscercadeti\/\">Mapa<\/a> &#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/NP%20CONFECOMER%C3%87%2023-04-20.pdf\">Nota de Prensa<\/a>)<br \/>\u2022 SEGUNDO TRAMO DE AVALES ICO PARA PYMES Y AUT\u00d3NOMOS (<a href=\"https:\/\/www.boe.es\/eli\/es\/res\/2020\/04\/10\/(1)\/dof\/spa\/pdf\">Resoluci\u00f3n del Consejo de Ministros<\/a> &#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/segundo_tramo_ico_consejo_ministros.pdf\">Circular segundo tramo ICO<\/a>)<br \/>\u2022 <a href=\"https:\/\/www--sepe--es.insuit.net\/HomeSepe\/COVID-19\/informacion-empresas.html\">SEPE: Informaci\u00f3n para empresas con ERTE<\/a><\/p>\n<p><strong>22\/04\/2020: Nuevas medidas de apoyo a aut\u00f3nomos y pymes<\/strong><br \/>\u2022 <a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/04\/22\/pdfs\/BOE-A-2020-4554.pdf\">Nuevas medidas del Gobierno de apoyo a pymes y aut\u00f3nomos<\/a><br \/>\u2022 <a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/04\/22\/pdf\/2020_2941.pdf\">Convocatoria L\u00ednea de Financiaci\u00f3n Bonificada IVF-liquidez Covid-19<\/a><\/p>\n<p><strong>19\/04\/2020: Ayudas para comercio de Ayuntamientos<\/strong><br \/>\u2022 <a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/MODELO-BASES-CASTELLANO.pdf\">MODELO DE BASES REGULADORAS Y CONVOCATORIA PARA LA CONCESI\u00d3N DE SUBVENCIONES DESTINADAS A APOYAR A LAS PERSONAS AUT\u00d3NOMAS, MICROEMPRESAS Y PEQUE\u00d1AS EMPRESAS PARA HACER FRENTE A LOS EFECTOS ORIGINADOS POR EL CORONAVIRUS COVID-19<\/a><\/p>\n<p><strong>17\/04\/2020: <a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/CIRCULAR-AYUDAS-CONFECOMERC.pdf\">CIRCULAR: RESUMEN AYUDAS, SOLICITUD CR\u00c9DITO Y PR\u00c9STAMOS, APLAZAMIENTOS Y MORATORIAS<\/a><\/strong><\/p>\n<p><strong>17\/04\/2020: Aplazamiento tributos y resumen ayudas por COVID-19<\/strong><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/aplazamiento_pagos_tributarios.pdf\">Resumen aplazamientos tributarios<\/a><br \/>\u2022 <a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/04\/15\/pdfs\/BOE-A-2020-4448.pdf\">Real Decreto-ley 14\/2020<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/Cuadro%20calendario%20pagos%20%2815-04-20%29.pdf\">Calendario obligaciones tributarias<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/CIRCULAR%20AYUDAS%20CONFECOMERC.pdf\">Resumen de ayudas para pymes y aut\u00f3nomos afectados por COVID-19<\/a><\/p>\n<p><strong>10\/04\/2020: <\/strong><a href=\"http:\/\/confecomercnews.es\/images\/files\/faq_ayudas_Labora_10042020.pdf\">PREGUNTAS Y RESPUESTAS FRECUENTES SOBRE LA SOLICITUD DE AYUDAS A AUT\u00d3NOMOS AFECTADOS POR COVID-19 DE LABORA GVA<\/a><\/p>\n<p><strong>09\/04\/2020: Instrucciones sobre ayudas Labora, aclaraciones Seguridad Social, derechos consumidores y encuesta pymes<\/strong><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/aclaraciones_ayudas_labora_09042020.pdf\">INSTRUCCIONES DE LABORA SOBRE LA APLICACI\u00d3N DE LAS AYUDAS PARA AUT\u00d3NOMOS AFECTADOS POR COVID-19<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/Respuesta%20TGSS%20a%20consulta.pdf\">\u00daLTIMAS ACLARACIONES DE LA TGSS<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/2020_-_04_-_02_Actualizacion_nota_derechos_consumidores_RDL_10_2020%20%28002%29.pdf\">DERECHOS DE CONSUMIDORES Y USUARIOS ANTE LA SITUACI\u00d3N PROVOCADA POR EL CORONAVIRUS<\/a><br \/>\u2022 <a href=\"https:\/\/cepymenews.es\/la-pyme-habla\/\">ENCUESTA CEPYME SOBRE LAS MEDIDAS FRENTE AL COVID-19<\/a><\/p>\n<p><strong>08\/04\/2020: Cuotas auton\u00f3mos marzo-junio, gu\u00eda ERTE, l\u00edneas ICO, alerta fraude Inspecci\u00f3n Trabajo y m\u00e1s<\/strong><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/aclaraciones_cuota_autonomos_08042020.pdf\">Aclaraciones sobre la cotizaci\u00f3n de aut\u00f3nomos afectados por COVID-19<\/a><br \/>\u2022 GU\u00cdA SOBRE SOLICITUD DE PRESTACI\u00d3N POR DESEMPLEO DE TRABAJADORES AFECTADOS POR ERTE: <a href=\"http:\/\/confecomercnews.es\/images\/files\/Hoja%20Informativa%20Empresas%20ERTE.pdf\">Hoja informativa empresas ERTE<\/a> &#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/Guia-Basica-Solicitud-Colectiva.pdf\">Gu\u00eda b\u00e1sica solicitud colectiva<\/a><br \/>\u2022 <a href=\"https:\/\/www.ico.es\/web\/ico\/linea-avales\">ACLARACIONES L\u00cdNEAS ICO<\/a><br \/>\u2022 ALERTA FRAUDE CORREO ELECTR\u00d3NICO INSPECCI\u00d3N DE TRABAJO<br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/260-8%20LG%202020.%20%20Reuniones%20societarias%20telem%C3%A1ticas.pdf\">ACLARACIONES SOBRE REUNIONES SOCIETARIAS TELEM\u00c1TICAS<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/Cartela%20planifica.jpg\">CAMPA\u00d1A SEMANA SANTA #PLANIFICATUSCOMPRAS<\/a><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/telfcontacto%20080420%281%29.pdf\">WEBS Y APP INFORMACI\u00d3N<\/a><\/p>\n<p><strong>06\/04\/2020: Bases ayudas Labora para aut\u00f3nomos, bono social y apoyo campa\u00f1a colectivos vulnerables<\/strong><br \/>\u2022 <a href=\"http:\/\/confecomercnews.es\/images\/files\/bases_ayudas_labora_covid19.pdf\">BASES AYUDAS LABORA PARA AUT\u00d3NOMOS AFECTADOS POR COVID-19<\/a><br \/>\u2022 <a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/04\/04\/pdfs\/BOE-A-2020-4292.pdf\">BONO SOCIAL PARA\u00a0AUT\u00d3NOMOS<\/a><br \/>\u2022 APOYO CAMPA\u00d1A INSTITUCIONAL COLECTIVOS VULNERABLES (<a href=\"http:\/\/confecomercnews.es\/images\/files\/Cartel%20Escoltem%20la%20teua%20veu%20A3%281%29.pdf\">Cartel Escoltem la teua veu<\/a> &#8211; <a href=\"http:\/\/confecomercnews.es\/images\/files\/AF%20Cartel%20A3%20Cuarentena%20.pdf%281%29.pdf\">Cartel Atenci\u00f3n v\u00edctmas violencia de g\u00e9nero<\/a>)<\/p>\n<p><strong>04\/04\/2020 <a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/bases_ayudas_labora_covid19.pdf\">Publicadas las bases de las ayudas del Consell para aut\u00f3nomos afectados por COVID-19<\/a><\/strong><\/p>\n<p><strong>03\/04\/2020 <a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/decreto_ayudas_gva.pdf\">Subvenciones aut\u00f3nomos GVA-LABORA<\/a><\/strong><\/p>\n<p><strong>02\/04\/2020: \u00daLTIMA INFORMACI\u00d3N AYUDAS AYUNTAMIENTO DE VAL\u00c8NCIA<\/strong><br \/>\u2022 <a href=\"https:\/\/rec.redsara.es\/registro\/action\/are\/acceso.do\">ENLACE SEDE ELECTR\u00d3NICA DEL MINISTERIO\u00a0<\/a><br \/>\u2022 <a href=\"https:\/\/www.valencia.es\/ayuntamiento\/tablon_anuncios.nsf\/vDocumentosWebTablon\/A4D16CDFE742F59EC125853800418FFA?OpenDocument&amp;lang=2&amp;nivel=5_1\">TABL\u00d3N DE ANUNCIOS AYUNTAMIENTO DE VALENCIA\u00a0<\/a><br \/>\u2022 <a href=\"http:\/\/valenciactiva.valencia.es\/es\/valencia-emprende\/subvenciones-re-activa-valencia\">WEB VAL\u00c8NCIA-ACTIVA\u00a0<\/a><\/p>\n<p><strong>02\/04\/2020: <a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/CIRCULAR_SGR_02042020.pdf\">C\u00f3mo solicitar financiaci\u00f3n circulante para pymes y aut\u00f3nomos SGR-IVF<\/a><\/strong><br \/>\u2022 FINANCIACI\u00d3N CIRCULANTE PARA PYMES Y AUT\u00d3NOMOS SGR-IVF<br \/>\u2022 Bases de la convocatoria<br \/>\u2022 Circular Financiaci\u00f3n Circulante para pymes y aut\u00f3nomos SGR-IVF<br \/>\u2022 Solicitud SGR Aut\u00f3nomo<br \/>\u2022 Solicitud SGR Pyme<br \/>\u2022 Plantilla Tabla de obligaciones<br \/>\u2022 Cuadro principales l\u00edneas IVF<\/p>\n<p><strong>01\/04\/2020: <a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/04\/circular_COVID19_CONFECOMER\u00c7CV_01042020.pdf\">Aplazamiento pagos y medidas apoyo aut\u00f3nomos, financiaci\u00f3n SGR y gu\u00eda venta a distancia<\/a><\/strong><br \/>\u2022 EL GOBIERNO APRUEBA UN NUEVO PAQUETE DE MEDIDAS PARA AUT\u00d3NOMOS Y PYMES<br \/>\u2022 AF\u00cdN-SGR CUBRIR\u00c1 LAS P\u00c9RDIDAS DE MARZO A MAYO DE AUT\u00d3NOMOS Y PYMES<br \/>\u2022 GU\u00cdA DE RECOMENDACIONES PARA EL DESARROLLO DE LA ACTIVIDAD COMERCIAL A DISTANCIA<br \/>\u2022 AMPLIACI\u00d3N DE PLAZO PARA RESOLVER Y NOTIFICAR ERTE<br \/>\u2022 INSTRUCCIONES DEL SEPE SOBRE LAS MEDIDAS DE PROTECCI\u00d3N POR DESEMPLEO<br \/>\u2022 EL MINISTERIO DE TRABAJO ACLARA LAS \u00daLTIMAS MEDIDAS DE CONTENCI\u00d3N<br \/>\u2022 FAQ ACTIVIDADES PERMITIDAS Y DIRECTORIO SOBRE EL COVID-19<\/p>\n<p><strong>01\/04\/2020: Contacto proveedores EPI para el comercio<\/strong><br \/>\u2022 \u00bfC\u00f3mo hacer un pedido?<br \/>\u2022 Facturaci\u00f3n y forma de pago<br \/>\u2022 Gastos de env\u00edo y forma de entrega<\/p>\n<p><strong>31\/03\/2020: CAMBIO DE LOS FESTIVOS APERTURABLES PREVISTOS PARA SEMANA SANTA\u00a0<\/strong><\/p>\n<p><strong>31\/03\/2020: SUBVENCIONES AYUNTAMIENTO VAL\u00c8NCIA, MODIFICACI\u00d3N AVALES IVF Y FAQ AVALES ICO<\/strong><br \/>\u2022 AYUDAS AYUNTAMIENTO DE VAL\u00c8NCIA ANTE EL COVID-19: <a href=\"https:\/\/drive.google.com\/file\/d\/1ev0C2NNsxWhU7Vi7rnEh-FARqwvoOU5W\/view\">Documento resumen Ayudas Reactiva<\/a> &#8211; <a href=\"https:\/\/bop.dival.es\/bop\/drvisapi.dll\">Texto Oficial publicado en BOP<\/a><br \/><a href=\"http:\/\/confecomercnews.es\/images\/files\/IVF%20marzo%202020.pdf\">\u2022 Cuadro resumen modificaci\u00f3n avales IVF<\/a><br \/><a href=\"http:\/\/confecomercnews.es\/images\/files\/FAQ_lineadeavales.pdf\">\u2022 FAQ Avales ICO<\/a><\/p>\n<p><strong>31\/03\/2020: <a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/aclaraciones-RDL-29032020-1.pdf\">ACLARACIONES SOBRE RDL 10\/2020, DE 29 DE MARZO<\/a><\/strong><br \/>\u2022 Resumen<br \/>\u2022 Modelo de declaraci\u00f3n responsable<br \/>\u2022 Orden SND\/307\/2020, de 30 de marzo<\/p>\n<p><b>30\/03\/2020: Aclaraciones sobre las pr\u00f3ximas obligaciones fiscales y laborales de las pymes y aut\u00f3nomos de comercio<\/b><br \/>\u2022 \u00bfC\u00f3mo afecta al comercio y servicios?<br \/>\u2022 INTERPRETACI\u00d3N DE LA DIRECCI\u00d3N GENERAL DE TRABAJO SOBRE ERTE DE FUERZA MAYOR<\/p>\n<p><strong>27\/03\/2020:Nuevas limitaciones a la movilidad de los trabajadores<\/strong><br \/>\u2022 <a href=\"https:\/\/drive.google.com\/file\/d\/1lJ-3G2R8cnXs_4ibnv0-nMEpdUaFRP2S\/view\">Documento aclaraciones obligaciones fiscales y laborales pymes y aut\u00f3nomos comercio<\/a><\/p>\n<p><strong>26\/03\/2020: Instrucci\u00f3n sobre la suspensi\u00f3n de contartos y reducci\u00f3n de jornada<\/strong><br \/>\u2022 Instrucci\u00f3n actualizada de la DG Trabajo<br \/>\u2022 DETALLE CARACTER\u00cdSTICAS AVALES ICO<br \/>\u2022 MEDIDAS AGENCIA TRIBUTARIA VALENCIANA<br \/>\u2022 INICIATIVA PARA QUE LAS DISTRIBUIDORAS EL\u00c9CTRICAS COBREN LA POTENCIA REAL DEMANDADA DURANTE EL COVID-19<\/p>\n<p><strong>26\/03\/2020: <a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/Circular-desarrollo-avales-ico-26032020.pdf\">Circular desarrollo avales ICO<\/a><\/strong><br \/>Te detallamos a continuaci\u00f3n las principales caracter\u00edsticas de estos avales:<br \/>\u2022 Finalidad<br \/>\u2022 Importes y distribuci\u00f3n<br \/>\u2022 Caracter\u00edsticas de los pr\u00e9stamos<br \/>\u2022 Importe m\u00e1ximo pr\u00e9stamo<br \/>\u2022 An\u00e1lisis del perfil de riesgos y condiciones de elegibilidad de la operaci\u00f3n<br \/>\u2022 Fuentes de financiaci\u00f3n<br \/>\u2022 Porcentajes m\u00e1ximos de aval<br \/>\u2022 Remuneraci\u00f3n del aval<br \/>\u2022 Plazo de solicitud de avales<br \/>\u2022 Plazo de vencimiento<br \/>\u2022 Otros aspectos relevantes<\/p>\n<p><strong>25\/03\/2020: <a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/Circular-avales-ico-25032020.pdf\">Circular avales ICO<\/a><br \/><\/strong>\u2022 \u00bfQui\u00e9n puede solicitarlo?<br \/>\u2022 Plazo<br \/>\u2022 \u00bfQu\u00e9 cubre el aval?<br \/>\u2022 Tipo de inter\u00e9s<br \/>\u2022 Vigencia<br \/>\u2022 \u00bfC\u00f3mo solicitarlo?<br \/>\u2022 Compromiso de las entidades financieras<\/p>\n<p><strong>23\/03\/2020: V\u00eddeo apoyo comercio y dudas actividades actualizadas<\/strong><br \/>\u2022 V\u00eddeo apoyo al peque\u00f1o comercio<br \/>\u2022 Dudas sobre actividades permitidas durante el Estado de Alerta<br \/>\u2022 M\u00e1s informaci\u00f3n: Informe Abogac\u00eda General del Estado sobre cuestiones planteadas sobre la interpretaci\u00f3n del RD 463\/2020,\u00a0 modificado por RD 465\/2020, Orden TMA\/264\/2020, de 20 de marzo, por la que se modifica la Orden TMA\/ 259\/2020, de 19 de marzo, por la que se dictan instrucciones sobre transporte por carretera, Orden SND\/257\/2020, de 19 de marzo, por la que se declara la suspensi\u00f3n de apertura al p\u00fablico de establecimientos de alojamiento tur\u00edstico, de acuerdo con el art\u00edculo 10.6 del Real, Decreto 463\/2020, de 14 de marzo, por el que se declara el estado de alarma para la gesti\u00f3n de la situaci\u00f3n de crisis sanitaria ocasionada por el COVID-19, Informe &#8220;Fake News&#8221; CITCO (noticias falsas)<\/p>\n<p><strong>20\/03\/2020: Dudas medidas de car\u00e1cter laboral y campa\u00f1a apoyo comercio desde casa<\/strong><br \/>\u2022 Preguntas frecuentes en materia laboral<br \/>\u2022 Cambio en el Decreto del Estado de alarma<br \/>\u2022 Campa\u00f1a al apoyo del peque\u00f1o comercio desde casa<\/p>\n<p><strong>18\/03\/2020: Medidas urgentes en materia laboral para hacer frente al impacto econ\u00f3mico y social del COVID-19<\/strong><br \/>\u2022 Resumen elaborado por Confecomer\u00e7 CV de las medidas aprobadas en el aspecto laboral<br \/>\u2022 Real Decreto-ley 8\/2020 de 17 de marzo de medidas urgentes extraordinarias para hacer frente al impacto econ\u00f3mico y social del COVID-19<\/p>\n<p><strong>18\/03\/2020: Medidas urgentes en materia de flexibilizaci\u00f3n para hacer frente al impacto econ\u00f3mico y social del COVID-19<\/strong><br \/>\u2022 Resumen medidas de flexibilizaci\u00f3n<br \/>\u2022 Resumen medidas laborales<br \/>\u2022 Real Decreto-ley 8\/2020 de 17 de marzo de medidas urgentes extraordinarias para hacer frente al impacto econ\u00f3mico y social del COVID-19<\/p>\n<p><strong>17\/03\/2020: Protocolos alimentaci\u00f3n y \u00faltimas dudas sobre COVID-19<\/strong><br \/>\u2022 Infogr\u00e1fico elaborado por Confecomer\u00e7 CV<br \/>\u2022 Documento FAQ: resoluci\u00f3n de dudas y consultas de comercios<\/p>\n<p><strong>16\/03\/2020: Documentos de inter\u00e9s COVID-19<\/strong><br \/>\u2022 Nota interna expedientes suspensivos y reducci\u00f3n de jornada<br \/>\u2022 Disposiciones publicadas en el BOE<br \/>\u2022 Modelo certificado de pertenencia del trabajador\/a a la empresa a efectos desplazamientos<br \/>\u2022 Nota aclaratoria servicio comidas para llevar<br \/>\u2022 Manual para el Sector Comercio frente al escenario del COVID-19. Recomendaciones y buenas pr\u00e1cticas<\/p>\n<p><strong>15\/03\/2020: Medidas de contenci\u00f3n en el \u00e1mbito de la actividad comercial ante el COVID-19<\/strong><br \/>\u2022 Real Decreto 463\/2020 de 14 de marzo, por el que se declara el estado de alarma para la gesti\u00f3n de la situaci\u00f3n de crisis sanitaria ocasionada por el COVID-19 (suspendida toda actividad comercial minorista con excepciones)<\/p>\n<p><strong>15\/03\/2020: \u00daltima informaci\u00f3n sobre COVID-19<\/strong><br \/>\u2022 Documento consultas aperturas, medidas de movilidad y a nivel laboral<br \/>\u2022 Comunicado Oficial de la CEOE y Cepyme<br \/>\u2022 Real Decreto 463\/2020 de 14 de marzo por Estado de Alarma<\/p>\n<p><strong>15\/03\/2020: Documentos de inter\u00e9s COVID-19<\/strong><br \/>\u2022 Circular. Medidas del Estado de Alarma que afectan a las empresas<br \/>\u2022 Faq: Preguntas frecuentes sobre el Estado de Alarma<\/p>\n<p><strong>14\/03\/2020: \u00daltimas medidas COVID-19<\/strong><br \/>\u2022 Declaraci\u00f3n institucional del Presidente del Gobierno<br \/>\u2022 Resoluci\u00f3n suspensi\u00f3n de clases, cierre de centros culturales, museos, teatros, bibliotecas y espacios de car\u00e1cter cultural, recreativo y de ocio<br \/>\u2022 Relaci\u00f3n completa de cierres (bares, discotecas, etc)<\/p>\n<p><strong>13\/03\/2020: Nota informativa Confecomer\u00e7 CV en relaci\u00f3n al COVID-19<\/strong><br \/>\u2022 Nota informativa Direcci\u00f3n General de Comercio<br \/>\u2022 Plan de Acci\u00f3n contra el COVID-19 de la Generalitat-Propuestas Econom\u00eda<br \/>\u2022 Real Decreto-ley 7\/2020 de 12 de marzo, por el que se adoptan medidas urgentes para responder al impacto econ\u00f3mico del COVID-19<br \/>\u2022 Resoluci\u00f3n de 11 de marzo de 2020, de la consellera de Sanidad Universal y Salud P\u00fablica, por la que se acuerdan medidas excepcionales para eventos festivos y de concentraci\u00f3n de personas, en la Comunitat Valenciana para limitar la propagaci\u00f3n y el contagio por el COVID-19<br \/>\u2022 Comunicado CEC<br \/>\u2022 Nota de Prensa Confecomer\u00e7 de medidas de apoyo al sector<\/p>\n<p><strong>13\/03\/2020: Instrucciones provisionales para solicitar el aplazamiento previsto en el Real Decreto Ley COVID-19<\/strong><br \/>\u2022 Manual de instrucciones provisionales<br \/>\u2022 Real Decreto-Ley 7\/2020 de 12 de marzo por el que se adoptan medidas urgentes para responder al impacto econ\u00f3mico de COVID-19.<br \/>13\/03\/2020: Informaci\u00f3n COVID19<br \/>\u2022 Cartel informativo conselleria (informaci\u00f3n garantizando el abastecimiento)<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;LINEAS ESPECIALES DE FINANCIACI\u00d3N CORONAVIRUS ASOCIADOS CONFECOMER\u00c7&#8221; _builder_version=&#8221;4.4.6&#8243;]<\/p>\n<ul>\n<li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/MEDIDAS-CAIXA-POPULAR.pdf\"><b>MEDIDAS CAIXA POPULAR DE AYUDAS A COMERCIO (27\/03\/2020)<\/b><\/a><\/li>\n<li><strong>CONFECOMER\u00c7 CV \/ CAIXA POPULAR<\/strong><\/li>\n<\/ul>\n<p>En respuesta a las peticiones realizadas, Caixa Popular ha activado una l\u00ednea de financiaci\u00f3n especial que puede ser de inter\u00e9s para los asociados afectados por el decreto de estado de alarma.<\/p>\n<p>Se trata de p\u00f3liza de cr\u00e9dito y prestamos personal (con carencia y sin carencia), sin comisiones de ning\u00fan tipo y con un tipo de inter\u00e9s del 2,5%.<\/p>\n<p>Los asociados interesados deben contactar con las oficinas de Caixa Popular.<\/p>\n<p>documentaci\u00f3n para tramitar la moratoria hipotecaria que nos remite Caixa Popular para informaci\u00f3n de los asociados.<br \/>\u2022 <a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/CAIXA-POPULAR_Informacion-para-entregar-a-los-Clientes.pdf\">Documentaci\u00f3n que debe aportar el cliente.<\/a><br \/>\u2022 <a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/CAIXA-POPULAR_Plantilla-Solicitud-de-an\u00e1lisis-de-la-aplicaci\u00f3n-de-moratoria-hipotecaria-del-RDL-8-2020.docx\">Plantilla de solicitud que hemos confeccionado Caixa Popular.<\/a><br \/>\u2022 <a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/CAIXA-POPULAR_modelo-declaracion-responsable.doc\">Modelo de declaraci\u00f3n responsable que debe aportar el cliente tambi\u00e9n confeccionada por Caixa Popular.<\/a><\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta p\u00e1gina recoge los comunicados y las circulares remitidas desde la Confecomer\u00e7 CV en relaci\u00f3n al coronavirus y facilita el acceso a toda la informaci\u00f3n oficial actualizada sobre el COVID-19.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":2437,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p>Esta p\u00e1gina recoge los comunicados y las circulares remitidas desde la Confecomer\u00e7 CV en relaci\u00f3n al coronavirus y facilita el acceso a toda la informaci\u00f3n oficial actualizada sobre el COVID-19:<\/p><ul><li><strong>DOCUMENTACI\u00d3N OFICIAL<\/strong><\/li><li><strong>INFORMACI\u00d3N COMERCIAL<\/strong><\/li><li><strong>RECOMENDACIONES-BUENAS PR\u00c1CTICAS<\/strong><\/li><li><strong>CIRCULARES INFORMATIVAS CONFECOMER\u00c7 CV<\/strong><\/li><li><strong>INFORMACI\u00d3N LABORAL-FISCAL<\/strong><\/li><li><strong>COMUNICADOS Y NOTAS DE PRENSA. PROPUESTAS Y MEDIDAS DEL SECTOR<\/strong><\/li><\/ul><p><img class=\"alignnone wp-image-2424\" src=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/info-coronavirus.png\" alt=\"\" width=\"768\" height=\"277\" \/><\/p><p><strong>DOCUMENTACI\u00d3N OFICIAL\u00a0<\/strong><\/p><ul><li><a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/03\/18\/pdfs\/BOE-A-2020-3828.pdf\">Real Decreto 465\/2020, de 17 de marzo, por el que se modifica el Real Decreto 463\/2020, de 14 de marzo, por el que se declara el estado de alarma para la gesti\u00f3n de la situaci\u00f3n de crisis sanitaria ocasionada por el COVID-19.<\/a><\/li><li><a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/03\/18\/pdfs\/BOE-A-2020-3824.pdf\">Real Decreto-ley 8\/2020, de 17 de marzo, de medidas urgentes extraordinarias para hacer frente al impacto econ\u00f3mico y social del COVID-19<\/a><\/li><li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/Refuerzo-del-Plan-de-Choque-econ\u00f3mico-por-el-COVID-19.pdf\">Refuerzo del Plan de Choque econ\u00f3mico por el COVID-19: El Gobierno moviliza 200.000 millones de euros para apoyar a trabajadores, familias y empresarios (17\/03\/2020)<\/a><\/li><li><a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/03\/15\/\">DISPOSICIONES PUBLICADAS EN EL BOE (15\/03\/2020)<\/a><\/li><li><a href=\"https:\/\/drive.google.com\/file\/d\/1RCUM4y-_cAgJ0rpgget0LpZD7fcqRBHT\/view\">REAL DECRETO 463\/2020 DE 14 DE MARZO POR ESTADO DE ALARMA (14\/03\/2020)<\/a><\/li><li><a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/03\/13\/pdf\/2020_2526.pdf\">DOGV- 13\/03\/2020: Suspensi\u00f3n temporal de la actividad educativa y formativa presencial<\/a><\/li><li><a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/03\/13\/pdf\/2020_2560.pdf\">DOGV- 13\/03\/2020: Medidas excepcionales para acontecimientos de car\u00e1cter cultural, recreativo o de ocio cierre de centros culturales<\/a><\/li><li><a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/03\/13\/pdf\/2020_2561.pdf\">DOGV- 13\/03\/2020: Medidas especiales de car\u00e1cter preventivo en materia de espect\u00e1culos p\u00fablicos, actividades recreativas, actividades socioculturales y establecimientos p\u00fablicos<\/a><\/li><li><a href=\"https:\/\/www.boe.es\/boe\/dias\/2020\/03\/13\/pdfs\/BOE-A-2020-3580.pdf\">Real Decreto-ley 7\/2020, de 12 de marzo, por el que se adoptan medidas urgentes para responder al impacto econ\u00f3mico del COVID-19<\/a><\/li><li><a href=\"http:\/\/www.dogv.gva.es\/datos\/2020\/03\/12\/pdf\/2020_2446.pdf\">DOGV - 12\/03\/2020: Medidas excepcionales para eventos festivos y de concentraci\u00f3n de personas, en la Comunitat Valenciana<\/a><\/li><\/ul><p><strong>INFORMACI\u00d3N COMERCIAL<\/strong><\/p><ul><li><a href=\"http:\/\/confecomercnews.es\/images\/files\/DUDAS%20SUSPENSI%C3%93N%20COMERCIO.pdf\">PREGUNTAS ACERCA DE LA APERTURA COMERCIAL SEG\u00daN REAL DECRETO 463\/2020 DE 14 DE MARZO POR EL QUE SE DECLARA EL ESTADO DE ALARMA PARA LA GESTI\u00d3N DE LA SITUACI\u00d3N DE CRISIS SANITARIA POR EL COVID-19<\/a><\/li><li><a href=\"http:\/\/confecomercnews.es\/images\/files\/Nota%20aclaratoria%20Servicio%20Comidas%20para%20llevar%281%29.pdf\">Nota aclaratoria respecto al servicio de comidas para llevar (15\/03\/2020)<\/a><\/li><li><a href=\"https:\/\/drive.google.com\/file\/d\/117AngC4BPFNr11VbqG16KeDOgovW9zeX\/view\">Certificado de pertenencia del trabajador\/a a la empresa a efectos de desplazamiento al centro de trabajo<\/a><\/li><\/ul><p><strong>RECOMENDACIONES-BUENAS PRACTICAS<\/strong><\/p><ul><li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/FAQ-ESTADO-ALARMA-18-03-20.pdf\">FAQ CONFECOMER\u00c7: PREGUNTAS FRECUENTES SOBRE EL ESTADO DE ALARMA - Actualizado 18\/03\/2020 a las 11:30h<\/a><\/li><li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/FAQ-comercio-17.03.2020.pdf\">CONSELLERIA COMERCIO PREGUNTAS Y RESPUESTAS M\u00c1S FRECUENTES SOBRE COMERCIO (FAQ): DECLARACI\u00d3N DEL ESTADO DE ALARMA POR EL CORONAVIRUS COVID-19\u00a0<\/a><\/li><li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/PROTOCOLO-DE-ACTUACI%C3%93N-EN-EL-COMERCIO.jpg\">\"Protocolo de actuaci\u00f3n en mercados y comercios de alimentaci\u00f3n\" (Infograf\u00eda)<\/a><\/li><li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/RECOMENDACIONES-CEC-COVID-19.pdf\">Manual para el sector comercio frente al escenario Covid-19-Recomendaciones y buenas pr\u00e1cticas\u00a0<\/a><\/li><\/ul><p><strong>CIRCU<\/strong><strong>LARES INFORMATIVAS CONFECOMER\u00c7 CV<\/strong><\/p><ul><li style=\"text-align: justify;\"><strong><a href=\"https:\/\/drive.google.com\/file\/d\/1hXnMsf4MrzDi-qLJQTWZ6FVuDEimiCG-\/view\">CIRCULAR CONFECOMER\u00c7. MEDIDAS DEL ESTADO DE ALARMA QUE AFECTAN A LAS EMPRESAS<\/a><\/strong><\/li><li><a href=\"https:\/\/www.cev.es\/noticias\/informacion-coronavirus\/\">Comunicados y las circulares remitidas desde la Confederaci\u00f3n Empresarial de la Comunitat Valenciana (CEV)\u00a0<\/a><\/li><\/ul><p><strong>INFORMACI\u00d3N LABORAL-FISCAL\u00a0<\/strong><\/p><ul><li><a href=\"http:\/\/confecomercnews.es\/images\/files\/2020-03-18%20-%20Medidas%20laborales%20-COVID19%20-%20BOE.pdf\">Resumen de Confecomer\u00e7 CV de las medidas laborales del REAL DECRETO-LEY 8\/2020, DE 17 DE MARZO<\/a><\/li><li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/Medidas-flexibilizacion-empresas-COVID-19.pdf\">Resumen de Confecomer\u00e7 CV otras medidas de flexibilizaci\u00f3n del REAL DECRETO-LEY 8\/2020, DE 17 DE MARZO<\/a><\/li><li><a href=\"http:\/\/confecomercnews.es\/images\/files\/NOTA_INTERNA_EXPEDIENTES_DE_REGULACIO%CC%81N_DE_EMPLEO_COVID_19_DGT_FINAL.pdf\">MINISTERIO DE TRABAJO Y ECONOM\u00cdA SOCIAL: NOTA INTERNA EXPEDIENTES SUSPENSIVOS Y REDUCCI\u00d3N DE JORNADA (12\/03\/2020)<\/a><\/li><li><a href=\"http:\/\/confecomercnews.es\/images\/files\/Solicitud%20de%20aplazamiento%20COVID19%20-%20Instrucciones%20provisionales%20AEAT.pdf\">AEAT: Instrucciones provisionales para solicitar el aplazamiento previsto en el Real Decreto Ley COVID-19<\/a><\/li><li><a href=\"https:\/\/twitter.com\/ConfecomercCV\/status\/1239886731513561088\">Bater\u00eda de preguntas frecuentes en el \u00e1mbito del #trabajo elaborado (Conselleria de Comercio GVA)<\/a><\/li><\/ul><p><strong>COMUNICADOS Y NOTAS DE PRENSA. PROPUESTAS Y MEDIDAS DEL SECTOR<\/strong><\/p><ul><li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/Comunicado-CEV-reunio%CC%81n-Palau.pdf\">Comunicado CEV: La CEV solicita rapidez y agilidad en la implementaci\u00f3n de lasmedidas incluidas en el Real Decreto Ley para que resulten eficaces (18\/03\/2020)<\/a><\/li><li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/200317-CEOE-CEPYME-ValoracionMedidasEconomicas.pdf\">CEO-CEPYME: Valoraci\u00f3n del paquete de medidas econ\u00f3micas (17\/03\/2020)<\/a><\/li><li><a href=\"https:\/\/confecomerc.es\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\">CONFECOMER\u00c7 CV DESTACA EL ESFUERZO QUE EST\u00c1 REALIZANDO EL PEQUE\u00d1O COMERCIO Y LOS MERCADOS MUNICIPALES Y LA RESPONSABILIDAD Y ACTITUD DEL SECTOR ANTE LA GRAVE CRISIS<\/a><\/li><li><a href=\"https:\/\/drive.google.com\/file\/d\/1WMXMA5CNda3_lbB3Yoc4RORSGGrrxoxX\/view\">COMUNICADO OFICIAL DE LA CEOE Y CEPYME (15\/03\/2020)<\/a><\/li><li><a href=\"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/COMUNICADO-DE-LA-CONFEDERACIO%CC%81N-ESPAN%CC%83OLA-DE-COMERCIO-y-recomendaciones-coronavirus.pdf\">COMUNICADO DE LA CONFEDERACI\u00d3N ESPA\u00d1OLA DE COMERCIO (CEC) SOBRE EL CORONAVIRUS Y RECOMENDACIONES<\/a><\/li><li><a href=\"https:\/\/confecomerc.es\/confecomerc-cv-lamenta-el-impacto-que-supone-el-aplazamiento-de-las-fallas\">Confecomer\u00e7 CV lamenta el impacto que supone el aplazamiento de las Fallas y la Magdalena<\/a><\/li><\/ul><p>\u00a0<\/p>","_et_gb_content_width":"","footnotes":""},"class_list":["post-2500","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informaci\u00f3n Coronavirus - Confecomer\u00e7<\/title>\n<meta name=\"description\" content=\"Esta p\u00e1gina recoge los comunicados y las circulares remitidas desde la Confecomer\u00e7 CV en relaci\u00f3n al coronavirus y facilita el acceso a toda la informaci\u00f3n oficial actualizada sobre el COVID-19.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/confecomerc.es\/va\/informacion-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informaci\u00f3n Coronavirus - Confecomer\u00e7\" \/>\n<meta property=\"og:description\" content=\"Esta p\u00e1gina recoge los comunicados y las circulares remitidas desde la Confecomer\u00e7 CV en relaci\u00f3n al coronavirus y facilita el acceso a toda la informaci\u00f3n oficial actualizada sobre el COVID-19.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/confecomerc.es\/va\/informacion-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"Confecomer\u00e7\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-06T08:42:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/confecomerc.es\/wp-content\/uploads\/2020\/03\/info-corona-confe.png?fit=1800%2C1265&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1265\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"29 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/informacion-coronavirus\\\/\",\"url\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/informacion-coronavirus\\\/\",\"name\":\"Informaci\u00f3n Coronavirus - Confecomer\u00e7\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/informacion-coronavirus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/informacion-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confecomerc.es\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/info-corona-confe.png\",\"datePublished\":\"2020-03-16T10:50:28+00:00\",\"dateModified\":\"2021-10-06T08:42:38+00:00\",\"description\":\"Esta p\u00e1gina recoge los comunicados y las circulares remitidas desde la Confecomer\u00e7 CV en relaci\u00f3n al coronavirus y facilita el acceso a toda la informaci\u00f3n oficial actualizada sobre el COVID-19.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/informacion-coronavirus\\\/#breadcrumb\"},\"inLanguage\":\"va-VA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/confecomerc.es\\\/va\\\/informacion-coronavirus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"va-VA\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/informacion-coronavirus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/confecomerc.es\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/info-corona-confe.png\",\"contentUrl\":\"https:\\\/\\\/confecomerc.es\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/info-corona-confe.png\",\"width\":1800,\"height\":1265,\"caption\":\"informacion coronavirus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/informacion-coronavirus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informaci\u00f3n Coronavirus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/#website\",\"url\":\"https:\\\/\\\/confecomerc.es\\\/\",\"name\":\"Confecomer\u00e7\",\"description\":\"Confederaci\u00f3 de Comer\u00e7 d\u2019alacant, Castell\u00f3 i Val\u00e8ncia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/confecomerc.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"va-VA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informaci\u00f3n Coronavirus - Confecomer\u00e7","description":"Esta p\u00e1gina recoge los comunicados y las circulares remitidas desde la Confecomer\u00e7 CV en relaci\u00f3n al coronavirus y facilita el acceso a toda la informaci\u00f3n oficial actualizada sobre el COVID-19.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/confecomerc.es\/va\/informacion-coronavirus\/","og_locale":"en_US","og_type":"article","og_title":"Informaci\u00f3n Coronavirus - Confecomer\u00e7","og_description":"Esta p\u00e1gina recoge los comunicados y las circulares remitidas desde la Confecomer\u00e7 CV en relaci\u00f3n al coronavirus y facilita el acceso a toda la informaci\u00f3n oficial actualizada sobre el COVID-19.\u00a0","og_url":"https:\/\/confecomerc.es\/va\/informacion-coronavirus\/","og_site_name":"Confecomer\u00e7","article_modified_time":"2021-10-06T08:42:38+00:00","og_image":[{"width":1800,"height":1265,"url":"https:\/\/i2.wp.com\/confecomerc.es\/wp-content\/uploads\/2020\/03\/info-corona-confe.png?fit=1800%2C1265&ssl=1","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"29 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/confecomerc.es\/va\/informacion-coronavirus\/","url":"https:\/\/confecomerc.es\/va\/informacion-coronavirus\/","name":"Informaci\u00f3n Coronavirus - Confecomer\u00e7","isPartOf":{"@id":"https:\/\/confecomerc.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/confecomerc.es\/va\/informacion-coronavirus\/#primaryimage"},"image":{"@id":"https:\/\/confecomerc.es\/va\/informacion-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/info-corona-confe.png","datePublished":"2020-03-16T10:50:28+00:00","dateModified":"2021-10-06T08:42:38+00:00","description":"Esta p\u00e1gina recoge los comunicados y las circulares remitidas desde la Confecomer\u00e7 CV en relaci\u00f3n al coronavirus y facilita el acceso a toda la informaci\u00f3n oficial actualizada sobre el COVID-19.\u00a0","breadcrumb":{"@id":"https:\/\/confecomerc.es\/va\/informacion-coronavirus\/#breadcrumb"},"inLanguage":"va-VA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/confecomerc.es\/va\/informacion-coronavirus\/"]}]},{"@type":"ImageObject","inLanguage":"va-VA","@id":"https:\/\/confecomerc.es\/va\/informacion-coronavirus\/#primaryimage","url":"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/info-corona-confe.png","contentUrl":"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/info-corona-confe.png","width":1800,"height":1265,"caption":"informacion coronavirus"},{"@type":"BreadcrumbList","@id":"https:\/\/confecomerc.es\/va\/informacion-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/confecomerc.es\/va\/confecomerc-cv\/"},{"@type":"ListItem","position":2,"name":"Informaci\u00f3n Coronavirus"}]},{"@type":"WebSite","@id":"https:\/\/confecomerc.es\/#website","url":"https:\/\/confecomerc.es\/","name":"Confecomer\u00e7","description":"Confederaci\u00f3 de Comer\u00e7 d\u2019alacant, Castell\u00f3 i Val\u00e8ncia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/confecomerc.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"va-VA"}]}},"_links":{"self":[{"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/pages\/2500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/comments?post=2500"}],"version-history":[{"count":0,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/pages\/2500\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/media\/2437"}],"wp:attachment":[{"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/media?parent=2500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}