{"id":265465,"date":"2024-11-21T12:37:53","date_gmt":"2024-11-21T11:37:53","guid":{"rendered":"https:\/\/confecomerc.es\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/"},"modified":"2024-11-21T12:37:53","modified_gmt":"2024-11-21T11:37:53","slug":"el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados","status":"publish","type":"post","link":"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/","title":{"rendered":"El Mercado Central de Val\u00e8ncia guarda este mediod\u00eda un minuto de silencio por las v\u00edctimas de la DANA y en apoyo a los mercados afectados"},"content":{"rendered":"<ul>\n<li><strong>Representantes de los mercados de Paiporta y Catarroja se unen a vendedores y clientes del Mercado Central para rendir homenaje a los compa\u00f1eros que han sufrido la devastaci\u00f3n de sus lugares de trabajo, sum\u00e1ndose al manifiesto de METRAE, la Confederaci\u00f3n de Mercados Tradicionales de Espa\u00f1a<\/strong><\/li>\n<li><strong>El encuentro concluir\u00e1, bajo la gran c\u00fapula, con un aplauso de solidaridad con los mercados que han sufrido las inundaciones, principalmente los de Paiporta y Catarroja, que a\u00fan no han podido abrir sus puertas<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Val\u00e8ncia, 20 de noviembre de 2024. <\/strong>El Mercado Central de Val\u00e8ncia acoger\u00e1 a partir de las 12 h de hoy bajo su gran c\u00fapula un acto de apoyo a los afectados por la DANA el pasado 29 de octubre, guardando un minuto de silencio por las v\u00edctimas y en apoyo a los mercados que han sufrido las inundaciones.<\/p>\n<p>Representantes de los mercados de Paiporta y Catarroja, los \u00fanicos que no han podido a\u00fan abrir sus puertas, acudir\u00e1n al encuentro para unirse a los vendedores y clientes del Mercado Central, con el fin de \u201crendir homenaje a los compa\u00f1eros que han sufrido la devastaci\u00f3n de sus lugares de trabajo\u201d, sum\u00e1ndose al manifiesto de METRAE, la Confederaci\u00f3n de Mercados Tradicionales de Espa\u00f1a, para mostrar la esperanza en la recuperaci\u00f3n y \u201crecobrar el esp\u00edritu de fortaleza y resiliencia que constituye la esencia, el ADN de los comerciantes, de los vendedores en mercados tradicionales\u201d.<\/p>\n<p>El encuentro, al que asistir\u00e1n la presidenta de Confemercats, Merche Gayet, y la presidenta de la Asociaci\u00f3n de Vendedores del Mercado Central de Val\u00e8ncia, Merche Puchades, se cerrar\u00e1 con un emotivo aplauso de solidaridad con los mercados que han padecido la DANA y por las v\u00edctimas y todas las personas que han sufrido y a\u00fan sufren las consecuencias de esta cat\u00e1strofe.<\/p>\n<p>Vendedores del mercado municipal de Paiporta mantuvieron el pasado s\u00e1bado una reuni\u00f3n de trabajo en el Mercado Central con la presidenta de la Asociaci\u00f3n de Vendedores y miembros de la Junta Directiva que les ofrecieron su ayuda en las gestiones para poderse relacionar con la administraci\u00f3n como asociaci\u00f3n de vendedores.<\/p>\n<p>Confemercats, la entidad de referencia de METRAE en la Comunidad Valenciana y miembro de Confecomer\u00e7, ha identificado hasta diez mercados afectados por la DANA, en los que trabajan cerca de 200 vendedores: Mercado de Albal, \u2060Mercado de Aldaia, \u2060Mercado de Alfafar, \u2060Mercado de Algemes\u00ed, Mercado de Benet\u00fasser, \u2060Mercado de Catarroja, \u2060Mercado de Chiva, \u2060Mercado de Paiporta, \u2060Mercado de Picanya y \u2060Mercado de Sedav\u00ed.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>MANIFIESTO DE METRAE<\/strong><\/p>\n<p><em>En primer lugar, queremos guardar un minuto de silencio en homenaje a todas las personas que han fallecido como consecuencia de los efectos de la DANA.<\/em><\/p>\n<p><em>Pero hoy queremos expresar algo m\u00e1s. Hoy es un d\u00eda para el silencio, s\u00ed, pero tambi\u00e9n para la esperanza y para iniciar el camino de recuperaci\u00f3n, recobrar el esp\u00edritu de fortaleza y resiliencia que constituye la esencia, el ADN de los comerciantes, de los vendedores en mercados tradicionales.<\/em><em>\u00a0<\/em><\/p>\n<p><em>Queremos trasladar esa fuerza a todos los compa\u00f1eros y compa\u00f1eras que tienen sus puestos de venta en las zonas afectadas por la DANA. Desde la Confederaci\u00f3n de Mercados Tradicionales de Espa\u00f1a hemos puesto en marcha esta acci\u00f3n con el prop\u00f3sito de rendir homenaje y mostrar nuestro calor y apoyo a todos nuestros compa\u00f1eros que han sufrido la devastaci\u00f3n de sus lugares de trabajo, que han perdido sus enseres, su maquinaria, su g\u00e9nero y sus puestos y, lo que es verdaderamente doloroso, la p\u00e9rdida de vidas humanas. Comerciantes que han vivido experiencias al l\u00edmite y han salvado la vida por muy poco y que ahora precisan de la ayuda de todos para sacar sus establecimientos del fango, para reconstruirse, para volver a ser quienes fueron\u2026<\/em><\/p>\n<p><em>Tenemos que recordar que los mercados no solo formamos parte del tejido comercial de nuestros pueblos y ciudades, sino que somos parte esencial de su modo de vida y en ese sentido cuidar de nosotros, preservar nuestra identidad centenaria y apostar por nuestro futuro es una manera de construir sociedades m\u00e1s amables y mejor vertebradas.<\/em><\/p>\n<p><em>Todav\u00eda hay mercados, como los de Catarroja o Paiporta, que 24 d\u00edas despu\u00e9s de la riada no solo no han podido abrir sus puertas, sino que no tienen expectativas de hacerlo a corto plazo. Y, en ese sentido, queremos instar a las autoridades municipales a no escatimar esfuerzos y ofrecer una batalla decidida hasta que de nuevo esas instalaciones sean abiertas y h\u00e1biles para su actividad. Y adem\u00e1s les emplazamos a realizar iniciativas orientadas a mejorar la imagen y la proyecci\u00f3n de comerciantes e instalaciones en la medida de sus posibilidades en todos los mercados afectados para que su vuelta a la normalidad se vea reforzada y sientan el apoyo de sus autoridades locales, un consuelo esencial puesto que son las que m\u00e1s cerca est\u00e1n de ellos. <\/em><\/p>\n<p><em>En homenaje al sufrimiento que han vivido y como medida de \u00e1nimo y reconocimiento vamos a darles un aplauso que les transmita nuestra solidaridad y fortaleza. Sabemos que vais a lograrlo \u00a1\u00c1nimo, compa\u00f1eros!<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Representantes de los mercados de Paiporta y Catarroja se unen a vendedores y clientes del Mercado Central para rendir homenaje a los compa\u00f1eros que han sufrido la devastaci\u00f3n de sus lugares de trabajo, sum\u00e1ndose al manifiesto de METRAE, la Confederaci\u00f3n de Mercados Tradicionales de Espa\u00f1a<\/p>\n","protected":false},"author":1,"featured_media":265464,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[613],"tags":[],"class_list":["post-265465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-associats-confecomerc-cv"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Mercado Central de Val\u00e8ncia guarda este mediod\u00eda un minuto de silencio por las v\u00edctimas de la DANA y en apoyo a los mercados afectados - Confecomer\u00e7<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Mercado Central de Val\u00e8ncia guarda este mediod\u00eda un minuto de silencio por las v\u00edctimas de la DANA y en apoyo a los mercados afectados - Confecomer\u00e7\" \/>\n<meta property=\"og:description\" content=\"Representantes de los mercados de Paiporta y Catarroja se unen a vendedores y clientes del Mercado Central para rendir homenaje a los compa\u00f1eros que han sufrido la devastaci\u00f3n de sus lugares de trabajo, sum\u00e1ndose al manifiesto de METRAE, la Confederaci\u00f3n de Mercados Tradicionales de Espa\u00f1a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/\" \/>\n<meta property=\"og:site_name\" content=\"Confecomer\u00e7\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-21T11:37:53+00:00\" \/>\n<meta name=\"author\" content=\"CONFECOMER\u00c7 CV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"CONFECOMER\u00c7 CV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\\\/\"},\"author\":{\"name\":\"CONFECOMER\u00c7 CV\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/#\\\/schema\\\/person\\\/23aa6211544dad9fa6ee269977b0a823\"},\"headline\":\"El Mercado Central de Val\u00e8ncia guarda este mediod\u00eda un minuto de silencio por las v\u00edctimas de la DANA y en apoyo a los mercados afectados\",\"datePublished\":\"2024-11-21T11:37:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\\\/\"},\"wordCount\":902,\"image\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confecomerc.es\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Vendedores-del-Mercado-de-Paiporta-acompanados-por-la-presidenta-y-miembros-de-Junta-Directiva-de-la-AVMC.jpeg\",\"articleSection\":[\"Associats Confecomer\u00e7 Cv\"],\"inLanguage\":\"va-VA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\\\/\",\"url\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\\\/\",\"name\":\"El Mercado Central de Val\u00e8ncia guarda este mediod\u00eda un minuto de silencio por las v\u00edctimas de la DANA y en apoyo a los mercados afectados - Confecomer\u00e7\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confecomerc.es\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Vendedores-del-Mercado-de-Paiporta-acompanados-por-la-presidenta-y-miembros-de-Junta-Directiva-de-la-AVMC.jpeg\",\"datePublished\":\"2024-11-21T11:37:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/#\\\/schema\\\/person\\\/23aa6211544dad9fa6ee269977b0a823\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\\\/#breadcrumb\"},\"inLanguage\":\"va-VA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/confecomerc.es\\\/va\\\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"va-VA\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/confecomerc.es\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Vendedores-del-Mercado-de-Paiporta-acompanados-por-la-presidenta-y-miembros-de-Junta-Directiva-de-la-AVMC.jpeg\",\"contentUrl\":\"https:\\\/\\\/confecomerc.es\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Vendedores-del-Mercado-de-Paiporta-acompanados-por-la-presidenta-y-miembros-de-Junta-Directiva-de-la-AVMC.jpeg\",\"width\":1844,\"height\":1501,\"caption\":\"Vendedores del Mercado de Paiporta acompa\u00f1ados por la presidenta y miembros de Junta Directiva de la AVMC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Mercado Central de Val\u00e8ncia guarda este mediod\u00eda un minuto de silencio por las v\u00edctimas de la DANA y en apoyo a los mercados afectados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/#website\",\"url\":\"https:\\\/\\\/confecomerc.es\\\/\",\"name\":\"Confecomer\u00e7\",\"description\":\"Confederaci\u00f3 de Comer\u00e7 d\u2019alacant, Castell\u00f3 i Val\u00e8ncia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/confecomerc.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"va-VA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/#\\\/schema\\\/person\\\/23aa6211544dad9fa6ee269977b0a823\",\"name\":\"CONFECOMER\u00c7 CV\",\"url\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/author\\\/confe-admin-cv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Mercado Central de Val\u00e8ncia guarda este mediod\u00eda un minuto de silencio por las v\u00edctimas de la DANA y en apoyo a los mercados afectados - Confecomer\u00e7","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/","og_locale":"en_US","og_type":"article","og_title":"El Mercado Central de Val\u00e8ncia guarda este mediod\u00eda un minuto de silencio por las v\u00edctimas de la DANA y en apoyo a los mercados afectados - Confecomer\u00e7","og_description":"Representantes de los mercados de Paiporta y Catarroja se unen a vendedores y clientes del Mercado Central para rendir homenaje a los compa\u00f1eros que han sufrido la devastaci\u00f3n de sus lugares de trabajo, sum\u00e1ndose al manifiesto de METRAE, la Confederaci\u00f3n de Mercados Tradicionales de Espa\u00f1a","og_url":"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/","og_site_name":"Confecomer\u00e7","article_published_time":"2024-11-21T11:37:53+00:00","author":"CONFECOMER\u00c7 CV","twitter_card":"summary_large_image","twitter_misc":{"Written by":"CONFECOMER\u00c7 CV","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/#article","isPartOf":{"@id":"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/"},"author":{"name":"CONFECOMER\u00c7 CV","@id":"https:\/\/confecomerc.es\/#\/schema\/person\/23aa6211544dad9fa6ee269977b0a823"},"headline":"El Mercado Central de Val\u00e8ncia guarda este mediod\u00eda un minuto de silencio por las v\u00edctimas de la DANA y en apoyo a los mercados afectados","datePublished":"2024-11-21T11:37:53+00:00","mainEntityOfPage":{"@id":"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/"},"wordCount":902,"image":{"@id":"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/#primaryimage"},"thumbnailUrl":"https:\/\/confecomerc.es\/wp-content\/uploads\/2024\/11\/Vendedores-del-Mercado-de-Paiporta-acompanados-por-la-presidenta-y-miembros-de-Junta-Directiva-de-la-AVMC.jpeg","articleSection":["Associats Confecomer\u00e7 Cv"],"inLanguage":"va-VA"},{"@type":"WebPage","@id":"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/","url":"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/","name":"El Mercado Central de Val\u00e8ncia guarda este mediod\u00eda un minuto de silencio por las v\u00edctimas de la DANA y en apoyo a los mercados afectados - Confecomer\u00e7","isPartOf":{"@id":"https:\/\/confecomerc.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/#primaryimage"},"image":{"@id":"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/#primaryimage"},"thumbnailUrl":"https:\/\/confecomerc.es\/wp-content\/uploads\/2024\/11\/Vendedores-del-Mercado-de-Paiporta-acompanados-por-la-presidenta-y-miembros-de-Junta-Directiva-de-la-AVMC.jpeg","datePublished":"2024-11-21T11:37:53+00:00","author":{"@id":"https:\/\/confecomerc.es\/#\/schema\/person\/23aa6211544dad9fa6ee269977b0a823"},"breadcrumb":{"@id":"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/#breadcrumb"},"inLanguage":"va-VA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/"]}]},{"@type":"ImageObject","inLanguage":"va-VA","@id":"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/#primaryimage","url":"https:\/\/confecomerc.es\/wp-content\/uploads\/2024\/11\/Vendedores-del-Mercado-de-Paiporta-acompanados-por-la-presidenta-y-miembros-de-Junta-Directiva-de-la-AVMC.jpeg","contentUrl":"https:\/\/confecomerc.es\/wp-content\/uploads\/2024\/11\/Vendedores-del-Mercado-de-Paiporta-acompanados-por-la-presidenta-y-miembros-de-Junta-Directiva-de-la-AVMC.jpeg","width":1844,"height":1501,"caption":"Vendedores del Mercado de Paiporta acompa\u00f1ados por la presidenta y miembros de Junta Directiva de la AVMC"},{"@type":"BreadcrumbList","@id":"https:\/\/confecomerc.es\/va\/el-mercado-central-de-valencia-guarda-este-mediodia-un-minuto-de-silencio-por-las-victimas-de-la-dana-y-en-apoyo-a-los-mercados-afectados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/confecomerc.es\/va\/confecomerc-cv\/"},{"@type":"ListItem","position":2,"name":"El Mercado Central de Val\u00e8ncia guarda este mediod\u00eda un minuto de silencio por las v\u00edctimas de la DANA y en apoyo a los mercados afectados"}]},{"@type":"WebSite","@id":"https:\/\/confecomerc.es\/#website","url":"https:\/\/confecomerc.es\/","name":"Confecomer\u00e7","description":"Confederaci\u00f3 de Comer\u00e7 d\u2019alacant, Castell\u00f3 i Val\u00e8ncia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/confecomerc.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"va-VA"},{"@type":"Person","@id":"https:\/\/confecomerc.es\/#\/schema\/person\/23aa6211544dad9fa6ee269977b0a823","name":"CONFECOMER\u00c7 CV","url":"https:\/\/confecomerc.es\/va\/author\/confe-admin-cv\/"}]}},"_links":{"self":[{"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/posts\/265465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/comments?post=265465"}],"version-history":[{"count":0,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/posts\/265465\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/media\/265464"}],"wp:attachment":[{"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/media?parent=265465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/categories?post=265465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/tags?post=265465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}