{"id":8155,"date":"2020-03-17T17:55:03","date_gmt":"2020-03-17T16:55:03","guid":{"rendered":"https:\/\/confecomerc.es\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/"},"modified":"2021-07-19T11:58:49","modified_gmt":"2021-07-19T10:58:49","slug":"confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio","status":"publish","type":"post","link":"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/","title":{"rendered":"Confecomer\u00e7 CV destaca el esfuerzo que est\u00e1 realizando el peque\u00f1o comercio y los mercados municipales y la responsabilidad y actitud del sector ante la grave crisis"},"content":{"rendered":"<ul>\n<li><strong><em>La patronal destaca la intensa labor de los peque\u00f1os comercios (alimentaci\u00f3n, tiendas de telecomunicaciones, \u00f3pticas, tintorer\u00edas, quioscos, etc) y de los Mercados Municipales que en estos d\u00edas est\u00e1n abasteciendo y atendiendo a las demandas de la ciudadan\u00eda<\/em><\/strong><\/li>\n<li><strong><em>La Confederaci\u00f3n anima a un sector al que el estado de alarma ha provocado el cierre de la gran mayor\u00eda de establecimientos y espera que el Gobierno adopte medidas contundentes acordes con la excepcionalidad de la situaci\u00f3n<\/em><\/strong><\/li>\n<\/ul>\n<p><em><u>Valencia, 17 de marzo de 2020<\/u><\/em><u>.<\/u>&#8211; <strong>La <\/strong><strong><em>Confederaci\u00f3 d\u00b4Empresaris del Comer\u00e7, Servicis i Aut\u00f2noms de la Comunitat Valenciana (CONFECOMER\u00c7 CV) <\/em><\/strong>ha destacado la responsabilidad y actitud del peque\u00f1o comercio y los Mercados, ante las directrices marcadas por el Gobierno en la crisis del coronavirus y el decreto de estado de alarma, y ha resaltado el esfuerzo y la intensa labor, llevado a cabo por los peque\u00f1os comerciantes de nuestra autonom\u00eda, que en estos \u00faltimos d\u00edas est\u00e1n trabajando intensamente realizando una gran labor para poder abastecer de recursos atendiendo a las demandas de la ciudadan\u00eda.<\/p>\n<p>Desde Confecomer\u00e7 CV se pone de manifiesto que desde el comercio \u201cnos sumamos a las decisiones tomadas por el Gobierno contra el virus, cumpliendo con responsabilidad de los mandatos derivados del estado de alarma que las autoridades han decretado\u201d. Esto supone un mazazo important\u00edsimo para el peque\u00f1o comercio y esperamos que desde el Gobierno y desde todas las instituciones a todos los niveles (nacional, auton\u00f3mico, provincial y local) se asuma la gravedad de la situaci\u00f3n para las cerca de 55.000 pymes y aut\u00f3nomos de comercio y que se adopten medidas que deben ser acordes con la excepcionalidad de la crisis\u201d, ha destacado el presidente de la Confederaci\u00f3n.<\/p>\n<p>\u201cEstamos preocupados por un escenario incierto, dado que no tenemos constancia del alcance de la situaci\u00f3n, al tiempo que nos solidarizamos con los afectados y sus familias, y trasladamos nuestro agradecimiento al colectivo de sanitarios, autoridades expertos y fuerzas de seguridad que trabajan para paliar esta crisis, que nos ha sobrevenido a todos\u201d. Reconocemos tambi\u00e9n la labor de los supermercados y sus trabajadores, pero tambi\u00e9n pedimos un merecid\u00edsimo reconocimiento por parte de las instituciones y los medios de comunicaci\u00f3n a la labor que est\u00e1n prestando los Mercados y los peque\u00f1os comercios que se les permite abrir y que con las infraestructuras, mucho m\u00e1s peque\u00f1as est\u00e1n haciendo un arduo esfuerzo por prestar servicio a la poblaci\u00f3n\u201d, ha destacado Torres.<\/p>\n<p>\u201cEl comercio minorista constituye un sector prioritario y estrat\u00e9gico para los territorios, compuesto por peque\u00f1as y medianas empresas y aut\u00f3nomos que dota de servicio y abastece a la poblaci\u00f3n, por lo que esperamos que se brinde apoyo firme por parte de la Administraci\u00f3n en estos momentos tan cr\u00edticos\u201d, ha apuntado el presidente de la Confederaci\u00f3n, Rafael Torres.<\/p>\n<p>La patronal auton\u00f3mica del comercio de la Comunitat Valenciana manifiesta que ha estado en todo momento en permanente contacto con la Direcci\u00f3n General de Comercio de la Generalitat Valenciana, as\u00ed como con el resto de instituciones, comunicando al sector y resolviendo las consultas generadas tras las decisiones adoptadas de manera inmediata, as\u00ed como informando de aquellas recomendaciones atendiendo a las directrices marcadas desde Salud P\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Confederaci\u00f3 d\u00b4Empresaris del Comer\u00e7, Servicis i Aut\u00f2noms de la Comunitat Valenciana (CONFECOMER\u00c7 CV) ha destacado la responsabilidad y actitud del peque\u00f1o comercio y los Mercados, ante las directrices marcadas por el Gobierno en la crisis del coronavirus y el decreto de estado de alarma, y ha resaltado el esfuerzo y la intensa labor, llevado a cabo por los peque\u00f1os comerciantes de nuestra autonom\u00eda, que en estos \u00faltimos d\u00edas est\u00e1n trabajando intensamente realizando una gran labor para poder abastecer de recursos atendiendo a las demandas de la ciudadan\u00eda. \u00a0<\/p>\n","protected":false},"author":1,"featured_media":2472,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[614,615],"tags":[3240,3223,2844,3241,3242],"class_list":["post-8155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-confecomerc-cv-va","category-notes-de-premsa","tag-comercio-cornavirus-va","tag-comercios-abiertos-coronavirus-va","tag-confecomerc-cv-va","tag-coronavirus-va","tag-covid-19-va"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Confecomer\u00e7 CV destaca el esfuerzo que est\u00e1 realizando el peque\u00f1o comercio y los mercados municipales y la responsabilidad y actitud del sector ante la grave crisis<\/title>\n<meta name=\"description\" content=\"CONFECOMER\u00c7 CV ha destacado la responsabilidad y actitud del peque\u00f1o comercio y los Mercados, ante las directrices marcadas por el Gobierno en la crisis del coronavirus y el decreto de estado de alarma, y ha resaltado el esfuerzo y la intensa labor, llevado a cabo por los peque\u00f1os comerciantes de nuestra autonom\u00eda, que en estos \u00faltimos d\u00edas est\u00e1n trabajando intensamente realizando una gran labor para poder abastecer de recursos atendiendo a las demandas de la ciudadan\u00eda. \u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confecomer\u00e7 CV destaca el esfuerzo que est\u00e1 realizando el peque\u00f1o comercio y los mercados municipales y la responsabilidad y actitud del sector ante la grave crisis\" \/>\n<meta property=\"og:description\" content=\"CONFECOMER\u00c7 CV ha destacado la responsabilidad y actitud del peque\u00f1o comercio y los Mercados, ante las directrices marcadas por el Gobierno en la crisis del coronavirus y el decreto de estado de alarma, y ha resaltado el esfuerzo y la intensa labor, llevado a cabo por los peque\u00f1os comerciantes de nuestra autonom\u00eda, que en estos \u00faltimos d\u00edas est\u00e1n trabajando intensamente realizando una gran labor para poder abastecer de recursos atendiendo a las demandas de la ciudadan\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/\" \/>\n<meta property=\"og:site_name\" content=\"Confecomer\u00e7\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-17T16:55:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-19T10:58:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/confecomerc.es\/wp-content\/uploads\/2020\/03\/esfuerzo-que-est\u00e1-realizando-el-peque\u00f1o-comercio_1.png?fit=1080%2C1080&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"CONFECOMER\u00c7 CV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Confecomer\u00e7 CV destaca el esfuerzo que est\u00e1 realizando el peque\u00f1o comercio y los mercados municipales y la responsabilidad y actitud del sector ante la grave crisis\" \/>\n<meta name=\"twitter:description\" content=\"CONFECOMER\u00c7 CV ha destacado la responsabilidad y actitud del peque\u00f1o comercio y los Mercados, ante las directrices marcadas por el Gobierno en la crisis del coronavirus y el decreto de estado de alarma, y ha resaltado el esfuerzo y la intensa labor, llevado a cabo por los peque\u00f1os comerciantes de nuestra autonom\u00eda, que en estos \u00faltimos d\u00edas est\u00e1n trabajando intensamente realizando una gran labor para poder abastecer de recursos atendiendo a las demandas de la ciudadan\u00eda.\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"CONFECOMER\u00c7 CV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\\\/\"},\"author\":{\"name\":\"CONFECOMER\u00c7 CV\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/#\\\/schema\\\/person\\\/23aa6211544dad9fa6ee269977b0a823\"},\"headline\":\"Confecomer\u00e7 CV destaca el esfuerzo que est\u00e1 realizando el peque\u00f1o comercio y los mercados municipales y la responsabilidad y actitud del sector ante la grave crisis\",\"datePublished\":\"2020-03-17T16:55:03+00:00\",\"dateModified\":\"2021-07-19T10:58:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\\\/\"},\"wordCount\":584,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confecomerc.es\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/esfuerzo-que-est\u00e1-realizando-el-peque\u00f1o-comercio_1.png\",\"keywords\":[\"comercio cornavirus\",\"comercios abiertos coronavirus\",\"confecomer\u00e7 cv\",\"coronavirus\",\"COVID-19\"],\"articleSection\":[\"Confecomer\u00e7 Cv\",\"Notes de premsa\"],\"inLanguage\":\"va-VA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\\\/\",\"url\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\\\/\",\"name\":\"Confecomer\u00e7 CV destaca el esfuerzo que est\u00e1 realizando el peque\u00f1o comercio y los mercados municipales y la responsabilidad y actitud del sector ante la grave crisis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/confecomerc.es\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/esfuerzo-que-est\u00e1-realizando-el-peque\u00f1o-comercio_1.png\",\"datePublished\":\"2020-03-17T16:55:03+00:00\",\"dateModified\":\"2021-07-19T10:58:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/#\\\/schema\\\/person\\\/23aa6211544dad9fa6ee269977b0a823\"},\"description\":\"CONFECOMER\u00c7 CV ha destacado la responsabilidad y actitud del peque\u00f1o comercio y los Mercados, ante las directrices marcadas por el Gobierno en la crisis del coronavirus y el decreto de estado de alarma, y ha resaltado el esfuerzo y la intensa labor, llevado a cabo por los peque\u00f1os comerciantes de nuestra autonom\u00eda, que en estos \u00faltimos d\u00edas est\u00e1n trabajando intensamente realizando una gran labor para poder abastecer de recursos atendiendo a las demandas de la ciudadan\u00eda. \u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\\\/#breadcrumb\"},\"inLanguage\":\"va-VA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"va-VA\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/confecomerc.es\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/esfuerzo-que-est\u00e1-realizando-el-peque\u00f1o-comercio_1.png\",\"contentUrl\":\"https:\\\/\\\/confecomerc.es\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/esfuerzo-que-est\u00e1-realizando-el-peque\u00f1o-comercio_1.png\",\"width\":1080,\"height\":1080,\"caption\":\"esfuerzo que est\u00e1 realizando el peque\u00f1o comercio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/confecomerc-cv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Confecomer\u00e7 CV destaca el esfuerzo que est\u00e1 realizando el peque\u00f1o comercio y los mercados municipales y la responsabilidad y actitud del sector ante la grave crisis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/#website\",\"url\":\"https:\\\/\\\/confecomerc.es\\\/\",\"name\":\"Confecomer\u00e7\",\"description\":\"Confederaci\u00f3 de Comer\u00e7 d\u2019alacant, Castell\u00f3 i Val\u00e8ncia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/confecomerc.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"va-VA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/confecomerc.es\\\/#\\\/schema\\\/person\\\/23aa6211544dad9fa6ee269977b0a823\",\"name\":\"CONFECOMER\u00c7 CV\",\"url\":\"https:\\\/\\\/confecomerc.es\\\/va\\\/author\\\/confe-admin-cv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confecomer\u00e7 CV destaca el esfuerzo que est\u00e1 realizando el peque\u00f1o comercio y los mercados municipales y la responsabilidad y actitud del sector ante la grave crisis","description":"CONFECOMER\u00c7 CV ha destacado la responsabilidad y actitud del peque\u00f1o comercio y los Mercados, ante las directrices marcadas por el Gobierno en la crisis del coronavirus y el decreto de estado de alarma, y ha resaltado el esfuerzo y la intensa labor, llevado a cabo por los peque\u00f1os comerciantes de nuestra autonom\u00eda, que en estos \u00faltimos d\u00edas est\u00e1n trabajando intensamente realizando una gran labor para poder abastecer de recursos atendiendo a las demandas de la ciudadan\u00eda. \u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/","og_locale":"en_US","og_type":"article","og_title":"Confecomer\u00e7 CV destaca el esfuerzo que est\u00e1 realizando el peque\u00f1o comercio y los mercados municipales y la responsabilidad y actitud del sector ante la grave crisis","og_description":"CONFECOMER\u00c7 CV ha destacado la responsabilidad y actitud del peque\u00f1o comercio y los Mercados, ante las directrices marcadas por el Gobierno en la crisis del coronavirus y el decreto de estado de alarma, y ha resaltado el esfuerzo y la intensa labor, llevado a cabo por los peque\u00f1os comerciantes de nuestra autonom\u00eda, que en estos \u00faltimos d\u00edas est\u00e1n trabajando intensamente realizando una gran labor para poder abastecer de recursos atendiendo a las demandas de la ciudadan\u00eda.","og_url":"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/","og_site_name":"Confecomer\u00e7","article_published_time":"2020-03-17T16:55:03+00:00","article_modified_time":"2021-07-19T10:58:49+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/i0.wp.com\/confecomerc.es\/wp-content\/uploads\/2020\/03\/esfuerzo-que-est\u00e1-realizando-el-peque\u00f1o-comercio_1.png?fit=1080%2C1080&ssl=1","type":"image\/png"}],"author":"CONFECOMER\u00c7 CV","twitter_card":"summary_large_image","twitter_title":"Confecomer\u00e7 CV destaca el esfuerzo que est\u00e1 realizando el peque\u00f1o comercio y los mercados municipales y la responsabilidad y actitud del sector ante la grave crisis","twitter_description":"CONFECOMER\u00c7 CV ha destacado la responsabilidad y actitud del peque\u00f1o comercio y los Mercados, ante las directrices marcadas por el Gobierno en la crisis del coronavirus y el decreto de estado de alarma, y ha resaltado el esfuerzo y la intensa labor, llevado a cabo por los peque\u00f1os comerciantes de nuestra autonom\u00eda, que en estos \u00faltimos d\u00edas est\u00e1n trabajando intensamente realizando una gran labor para poder abastecer de recursos atendiendo a las demandas de la ciudadan\u00eda.","twitter_misc":{"Written by":"CONFECOMER\u00c7 CV","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/#article","isPartOf":{"@id":"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/"},"author":{"name":"CONFECOMER\u00c7 CV","@id":"https:\/\/confecomerc.es\/#\/schema\/person\/23aa6211544dad9fa6ee269977b0a823"},"headline":"Confecomer\u00e7 CV destaca el esfuerzo que est\u00e1 realizando el peque\u00f1o comercio y los mercados municipales y la responsabilidad y actitud del sector ante la grave crisis","datePublished":"2020-03-17T16:55:03+00:00","dateModified":"2021-07-19T10:58:49+00:00","mainEntityOfPage":{"@id":"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/"},"wordCount":584,"commentCount":0,"image":{"@id":"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/#primaryimage"},"thumbnailUrl":"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/esfuerzo-que-est\u00e1-realizando-el-peque\u00f1o-comercio_1.png","keywords":["comercio cornavirus","comercios abiertos coronavirus","confecomer\u00e7 cv","coronavirus","COVID-19"],"articleSection":["Confecomer\u00e7 Cv","Notes de premsa"],"inLanguage":"va-VA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/","url":"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/","name":"Confecomer\u00e7 CV destaca el esfuerzo que est\u00e1 realizando el peque\u00f1o comercio y los mercados municipales y la responsabilidad y actitud del sector ante la grave crisis","isPartOf":{"@id":"https:\/\/confecomerc.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/#primaryimage"},"image":{"@id":"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/#primaryimage"},"thumbnailUrl":"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/esfuerzo-que-est\u00e1-realizando-el-peque\u00f1o-comercio_1.png","datePublished":"2020-03-17T16:55:03+00:00","dateModified":"2021-07-19T10:58:49+00:00","author":{"@id":"https:\/\/confecomerc.es\/#\/schema\/person\/23aa6211544dad9fa6ee269977b0a823"},"description":"CONFECOMER\u00c7 CV ha destacado la responsabilidad y actitud del peque\u00f1o comercio y los Mercados, ante las directrices marcadas por el Gobierno en la crisis del coronavirus y el decreto de estado de alarma, y ha resaltado el esfuerzo y la intensa labor, llevado a cabo por los peque\u00f1os comerciantes de nuestra autonom\u00eda, que en estos \u00faltimos d\u00edas est\u00e1n trabajando intensamente realizando una gran labor para poder abastecer de recursos atendiendo a las demandas de la ciudadan\u00eda. \u00a0","breadcrumb":{"@id":"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/#breadcrumb"},"inLanguage":"va-VA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/"]}]},{"@type":"ImageObject","inLanguage":"va-VA","@id":"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/#primaryimage","url":"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/esfuerzo-que-est\u00e1-realizando-el-peque\u00f1o-comercio_1.png","contentUrl":"https:\/\/confecomerc.es\/wp-content\/uploads\/2020\/03\/esfuerzo-que-est\u00e1-realizando-el-peque\u00f1o-comercio_1.png","width":1080,"height":1080,"caption":"esfuerzo que est\u00e1 realizando el peque\u00f1o comercio"},{"@type":"BreadcrumbList","@id":"https:\/\/confecomerc.es\/va\/confecomerc-cv-destaca-el-esfuerzo-que-esta-realizando-el-pequeno-comercio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/confecomerc.es\/va\/confecomerc-cv\/"},{"@type":"ListItem","position":2,"name":"Confecomer\u00e7 CV destaca el esfuerzo que est\u00e1 realizando el peque\u00f1o comercio y los mercados municipales y la responsabilidad y actitud del sector ante la grave crisis"}]},{"@type":"WebSite","@id":"https:\/\/confecomerc.es\/#website","url":"https:\/\/confecomerc.es\/","name":"Confecomer\u00e7","description":"Confederaci\u00f3 de Comer\u00e7 d\u2019alacant, Castell\u00f3 i Val\u00e8ncia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/confecomerc.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"va-VA"},{"@type":"Person","@id":"https:\/\/confecomerc.es\/#\/schema\/person\/23aa6211544dad9fa6ee269977b0a823","name":"CONFECOMER\u00c7 CV","url":"https:\/\/confecomerc.es\/va\/author\/confe-admin-cv\/"}]}},"_links":{"self":[{"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/posts\/8155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/comments?post=8155"}],"version-history":[{"count":0,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/posts\/8155\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/media\/2472"}],"wp:attachment":[{"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/media?parent=8155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/categories?post=8155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/confecomerc.es\/va\/wp-json\/wp\/v2\/tags?post=8155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}